{"id":392978,"date":"2022-07-11T10:20:00","date_gmt":"2022-07-11T13:20:00","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=392978"},"modified":"2022-07-11T10:20:00","modified_gmt":"2022-07-11T13:20:00","slug":"bndes-pode-dar-perdao-de-70-para-salvar-collor-bolsonarista-da-falencia","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/bndes-pode-dar-perdao-de-70-para-salvar-collor-bolsonarista-da-falencia\/","title":{"rendered":"BNDES pode dar perd\u00e3o de 70% para salvar Collor, bolsonarista, da fal\u00eancia"},"content":{"rendered":"<h2 class=\"article__headline marginBottom30\"><\/h2>\n<div class=\"article__lead\">\n<p>Collor foi flagrado recentemente fazendo uma defesa emocionada e vista como desproporcional de Bolsonaro em um ato pr\u00f3-governo em Macei\u00f3<\/p>\n<\/div>\n<figure><picture><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/2022062911068_734b691b65efe37f80495f9715b7cf4cc2e4187e6120cade272db61083b7708f.webp\" type=\"image\/webp\" media=\"(max-width: 680px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/2022062911068_734b691b65efe37f80495f9715b7cf4cc2e4187e6120cade272db61083b7708f.jpg\" type=\"image\/jpeg\" media=\"(max-width: 680px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/2022062911068_0fae5b8c2c2124b231fa9173a880f45436c9a746f490886eb6dd46194990cfc2.webp\" type=\"image\/webp\" media=\"(min-width: 681px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/2022062911068_0fae5b8c2c2124b231fa9173a880f45436c9a746f490886eb6dd46194990cfc2.jpg\" type=\"image\/jpeg\" media=\"(min-width: 681px)\" \/><img decoding=\"async\" title=\"Fernando Collor (Foto: Alan Santos\/PR)\" src=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/2022062911068_0fae5b8c2c2124b231fa9173a880f45436c9a746f490886eb6dd46194990cfc2.jpg\" alt=\"www.brasil247.com - Fernando Collor\" \/><\/picture><figcaption>Fernando Collor (Foto: Alan Santos\/PR)<\/figcaption><\/figure>\n<div class=\"article__text marginTop30\">\n<p>O BNDES (Banco Nacional de Desenvolvimento Econ\u00f4mico e Social) sinalizou ter chegado a um acordo com a OAM (Organiza\u00e7\u00e3o Arnon de Mello) para votar a favor do plano de recupera\u00e7\u00e3o judicial das empresas de comunica\u00e7\u00e3o da fam\u00edlia Collor de Mello em Alagoas. De acordo com o jornalista Carlos Madeiro, em reportagem do portal UOL, \u201co grupo negocia um total de R$ 64 milh\u00f5es em d\u00edvidas, das quais o banco p\u00fablico \u00e9 o maior credor\u201d.<\/p>\n<p>\u201cAp\u00f3s quase tr\u00eas meses de negocia\u00e7\u00e3o, um aditivo foi inclu\u00eddo ao plano pela empresa devedora na \u00faltima segunda-feira (4). A coluna teve acesso ao novo plano, em que a OAM altera a proposta inicial, prevendo um perd\u00e3o de 70% do d\u00e9bito original com o BNDES. S\u00f3 com o banco as d\u00edvidas totalizam R$ 14,4 milh\u00f5es, em valores de 2019\u201d, informa o jornalista.<\/p>\n<p>Se o BNDES aceitar a proposta, haver\u00e1 uma car\u00eancia de 12 meses para o in\u00edcio do pagamento e prazo de 126 meses at\u00e9 sua conclus\u00e3o.<\/p>\n<p>Procurado, o BNDES informou que n\u00e3o comenta negocia\u00e7\u00f5es em andamento. J\u00e1 a OAM n\u00e3o comentou at\u00e9 a \u00faltima atualiza\u00e7\u00e3o deste texto. Ele ser\u00e1 atualizado se houver uma resposta. O senador Fernando Collor de Mello, principal acionista do grupo, informou que n\u00e3o fala sobre a recupera\u00e7\u00e3o judicial.<\/p>\n<h2>Defesa emocionada<\/h2>\n<p>Coincid\u00eancia ou n\u00e3o, Collor foi flagrado recentemente fazendo uma defesa emocionada do governo de Jair \u00a0Bolsonaro, em um ato realizado em Macei\u00f3 pr\u00f3-governo,<\/p>\n<p>\u201cBolsonaro, Bolsonaro!\u201d, esbravejou o ex-presidente que sofreu um processo de impeachment em 1992 e ocupa uma vaga no Senado por Alagoas desde 2007.<\/p>\n<h2>Reveja o v\u00eddeo:<\/h2>\n<div class=\"embed-block\">\n<div class=\"twitter-tweet twitter-tweet-rendered\"><iframe id=\"twitter-widget-0\" class=\"\" title=\"Twitter Tweet\" src=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?creatorScreenName=brasil247&amp;dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfdHdlZXRfZWRpdF9iYWNrZW5kIjp7ImJ1Y2tldCI6Im9mZiIsInZlcnNpb24iOm51bGx9LCJ0ZndfcmVmc3JjX3Nlc3Npb24iOnsiYnVja2V0Ijoib2ZmIiwidmVyc2lvbiI6bnVsbH0sInRmd190d2VldF9yZXN1bHRfbWlncmF0aW9uXzEzOTc5Ijp7ImJ1Y2tldCI6InR3ZWV0X3Jlc3VsdCIsInZlcnNpb24iOm51bGx9LCJ0Zndfc2Vuc2l0aXZlX21lZGlhX2ludGVyc3RpdGlhbF8xMzk2MyI6eyJidWNrZXQiOiJpbnRlcnN0aXRpYWwiLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2V4cGVyaW1lbnRzX2Nvb2tpZV9leHBpcmF0aW9uIjp7ImJ1Y2tldCI6MTIwOTYwMCwidmVyc2lvbiI6bnVsbH0sInRmd19kdXBsaWNhdGVfc2NyaWJlc190b19zZXR0aW5ncyI6eyJidWNrZXQiOiJvZmYiLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3VzZXJfZm9sbG93X2ludGVudF8xNDQwNiI6eyJidWNrZXQiOiJmb2xsb3ciLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3R3ZWV0X2VkaXRfZnJvbnRlbmQiOnsiYnVja2V0Ijoib2ZmIiwidmVyc2lvbiI6bnVsbH19&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=1542109024346316801&amp;lang=pt&amp;origin=https%3A%2F%2Fwww.brasil247.com%2Fbrasil%2Fbndes-pode-dar-perdao-de-70-para-salvar-collor-bolsonarista-da-falencia&amp;sessionId=5af53911645c083f83d37958b5e309371372f5ad&amp;siteScreenName=brasil247&amp;theme=light&amp;widgetsVersion=b45a03c79d4c1%3A1654150928467&amp;width=550px\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<blockquote class=\"twitter-tweet\" data-twitter-extracted-i1657545361771529116=\"true\">\n<p dir=\"ltr\" lang=\"pt\">Bom dia para voc\u00ea que acreditou que Bolsonaro fosse a nova pol\u00edtica e agora tem que torcer pelo Collor.\u00a0<a href=\"https:\/\/t.co\/9zhAWi9IJ8\" target=\"_blank\" rel=\"noopener\">pic.twitter.com\/9zhAWi9IJ8<\/a><\/p>\n<div class=\"contentAd contentAd--noBackground marginBottom30\">\n<div class=\"marginTop10 adBackground\">\n<div id=\"div-gpt-ad-1560994868836-0\"><\/div>\n<\/div>\n<\/div>\n<p>\u2014 GugaNoblat (@GugaNoblat)\u00a0<a href=\"https:\/\/twitter.com\/GugaNoblat\/status\/1542109024346316801?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 29, 2022<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Procurado, o BNDES informou que n\u00e3o comenta negocia\u00e7\u00f5es em andamento. J\u00e1 a OAM n\u00e3o comentou at\u00e9 a \u00faltima atualiza\u00e7\u00e3o deste texto. Ele ser\u00e1 atualizado se houver uma resposta. O senador Fernando Collor de Mello, principal acionista do grupo, informou que n\u00e3o fala sobre a recupera\u00e7\u00e3o judicial.<\/p>\n<p>Defesa emocionada\u00a0<\/p>\n","protected":false},"author":5,"featured_media":392979,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-392978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/collor-ladrao.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=392978"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/392979"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=392978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=392978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=392978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}