{"id":393020,"date":"2022-07-11T16:35:32","date_gmt":"2022-07-11T19:35:32","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=393020"},"modified":"2022-07-11T16:35:32","modified_gmt":"2022-07-11T19:35:32","slug":"vale-do-sao-francisco-se-consolida-como-polo-de-atracao-de-eventos-esportivos","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/vale-do-sao-francisco-se-consolida-como-polo-de-atracao-de-eventos-esportivos\/","title":{"rendered":"Vale do S\u00e3o Francisco se consolida como polo de atra\u00e7\u00e3o de eventos esportivos"},"content":{"rendered":"<div dir=\"ltr\">\n<p style=\"text-align: justify;\" align=\"center\">\n<p style=\"text-align: justify;\">Refer\u00eancia internacional na produ\u00e7\u00e3o e exporta\u00e7\u00e3o de frutas, o Vale do S\u00e3o Francisco, tamb\u00e9m vem se revelando como um polo realizador de grandes eventos esportivos. Depois do sucesso da quarta edi\u00e7\u00e3o do Triathlon M\u00e3e Malvada&#8217;, realizado em Juazeiro &#8211; BA e Petrolina &#8211; PE, no \u00faltimo dia 10, a regi\u00e3o j\u00e1 se prepara para a &#8216;Copa Vela Juazeiro de Windsurf&#8217;, que acontece entre os dias 15 e 17 de julho, como parte das comemora\u00e7\u00f5es dos 144 anos de Juazeiro.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-393022 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/jogo-de-vela.jpg 1068w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">O &#8216;M\u00e3e Malvada&#8217;, reuniu mais de 500 atletas de v\u00e1rias regi\u00f5es do Brasil e de\u00a0 pa\u00edses a exemplo da Espanha, Portugal e Estados Unidos. Para a &#8216;Copa Vela Juazeiro de Windsurf&#8217;, que tem a chancela da Associa\u00e7\u00e3o Brasileira de Windsurf, a expectativa \u00e9 contar com a participa\u00e7\u00e3o de 100 velejadores de 6 estados do Nordeste, al\u00e9m de competidores do Rio de Janeiro, nas classes Windsurf, Windsurf Foil, Hobie Cat, Wing Foil, Dingue e classe aberta de monotipos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">De acordo com a triatleta e idealizadora do Triathlon M\u00e3e Malvada&#8217;, Ana Augusta, a promo\u00e7\u00e3o desses eventos, al\u00e9m de inserir o Vale do S\u00e3o Francisco no roteiro esportivo nacional e internacional, promove impactos significativos nas \u00e1reas do turismo, com\u00e9rcio, meio ambiente e seguran\u00e7a das cidades de Petrolina e Juazeiro. Compartilhando a mesma opini\u00e3o, o organizador da Copa Vela, Alexandre Lessa e o coordenador do evento, que\u00a0 tamb\u00e9m j\u00e1 est\u00e1 sendo chamado de &#8216;Campeonato Norte e Nordeste de Windsurf&#8217;, Dadau Barbosa, acrescentam que os grandes eventos esportivos trazem ainda in\u00fameros \u00a0benef\u00edcios para a sa\u00fade da popula\u00e7\u00e3o\u00a0 e de v\u00e1rios outros setores da economia.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para o diretor Financeiro e TI da Agrovale, Guilherme Cola\u00e7o Filho, a consolida\u00e7\u00e3o do Vale como refer\u00eancia nesta \u00e1rea \u00e9 tamb\u00e9m uma responsabilidade social do empresariado regional. Empresa do segmento sucroalcooleiro que patrocina o &#8216;Triathlon M\u00e3e Malvada&#8217; e a<\/p>\n<p style=\"text-align: justify;\">&#8216;Copa Vela Juazeiro de Windsurf&#8217;, a Agrovale tamb\u00e9m apoia competi\u00e7\u00f5es a exemplo da Meia Maratona Tiradentes, Corrida Tiradentinhos e a etapa regional do Campeonato Baiano de Ciclismo de Estrada\/ CRI. &#8220;Acreditamos na capacidade do esporte em transformar vidas, formar cidad\u00e3os mais conscientes e promover a inclus\u00e3o social&#8221;, concluiu Guilherme Cola\u00e7o Filho.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O &#8216;M\u00e3e Malvada&#8217;, reuniu mais de 500 atletas de v\u00e1rias regi\u00f5es do Brasil e de\u00a0 pa\u00edses a exemplo da Espanha, Portugal e Estados Unidos. Para a &#8216;Copa Vela Juazeiro de Windsurf&#8217;, que tem a chancela da Associa\u00e7\u00e3o Brasileira de Windsurf, a expectativa \u00e9 contar com a part<\/p>\n","protected":false},"author":5,"featured_media":393021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-393020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/corrida1.jpeg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=393020"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/393021"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=393020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=393020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=393020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}