{"id":393102,"date":"2022-07-12T10:05:37","date_gmt":"2022-07-12T13:05:37","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=393102"},"modified":"2022-07-12T10:05:37","modified_gmt":"2022-07-12T13:05:37","slug":"caixa-pagou-segurancas-e-internet-na-casa-de-guimaraes-diz-jornal","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/caixa-pagou-segurancas-e-internet-na-casa-de-guimaraes-diz-jornal\/","title":{"rendered":"Caixa pagou seguran\u00e7as e internet na casa de Guimar\u00e3es, diz jornal"},"content":{"rendered":"<div class=\"col-sm-12 ig-container_headerText\">\n<h1 id=\"noticia-titulo-h1\" class=\"noticia-titulo-h1-ig_V04\"><\/h1>\n<h2 id=\"noticia-olho\">Banco alega que medidas eram para evitar viol\u00eancia contra o ex-presidente<\/h2>\n<\/div>\n<div id=\"ad_billboard\" class=\"betOrBillboard\" data-google-query-id=\"CJKMx7W08_gCFbcAuQYdDdQHCw\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/economia.ig.com.br\/billboard_0__container__\"><\/div>\n<\/div>\n<div id=\"noticia-other\" class=\"noticia-other-ig_V04\">\n<div class=\"author-container\">\n<p>Por\u00a0<strong>Ag\u00eancia O Globo<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"contentNoticia\">\n<div class=\"main-content\">\n<div class=\"row\">\n<section class=\"noticia col-sm-12 plf-0\">\n<div id=\"noticia\">\n<div class=\"Noticia_Foto\">\n<figure class=\"foto-legenda \">\n<div class=\"foto-legenda-img\"><img loading=\"lazy\" decoding=\"async\" title=\"Pedro Guimar\u00e3es, ex-presidente da Caixa\" src=\"https:\/\/i0.statig.com.br\/bancodeimagens\/co\/gn\/8b\/cogn8bptfcnox6xicwseo1ezx.jpg\" alt=\"Pedro Guimar\u00e3es, ex-presidente da Caixa\" width=\"906\" height=\"509\" \/><\/div><figcaption class=\"foto-legenda-citacao \"><cite>Isac N\u00f3brega\/Presid\u00eancia<\/cite><\/p>\n<div class=\"foto-legenda-citacao-text\" data-gtm-vis-recent-on-screen-214867_1952=\"4974\" data-gtm-vis-first-on-screen-214867_1952=\"4974\" data-gtm-vis-total-visible-time-214867_1952=\"100\" data-gtm-vis-has-fired-214867_1952=\"1\">Pedro Guimar\u00e3es, ex-presidente da Caixa<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\"\">Al\u00e9m de\u00a0<a href=\"https:\/\/economia.ig.com.br\/2022-07-08\/deputados-tcu-obras-mansao-guimaraes-caixa.html\">reformas<\/a>\u00a0, a Caixa Econ\u00f4mica Federal pagou seguran\u00e7as e internet na mans\u00e3o do ex-presidente do banco,\u00a0<a href=\"https:\/\/economia.ig.com.br\/2022-06-29\/bolsonaro-pedro-guimaraes-assedio-caixa.html\" target=\"_blank\" rel=\"noopener\">Pedro Guimar\u00e3es<\/a>\u00a0, segundo reportagem do jornal Folha de S\u00e3o Paulo.<\/p>\n<p class=\"\">Os vigilantes ficam na casa sete dias por semana, 24 horas por dia, com turno de 44 horas semanais. Apenas o presidente da institui\u00e7\u00e3o tem esse benef\u00edcio.<\/p>\n<p class=\"\">O contrato com a empresa de seguran\u00e7a Confederal, assinado em 2021, prev\u00ea oito seguran\u00e7as para a presid\u00eancia do banco ao pre\u00e7o unit\u00e1rio de R$ 11,5 mil, o que representa R$ 91,4 mil por m\u00eas.<\/p>\n<p>Segundo o advogado de Guimar\u00e3es,\u00a0Jos\u00e9 Luis Oliveira Lima, a motiva\u00e7\u00e3o do refor\u00e7o na seguran\u00e7a foram amea\u00e7as direcionadas ao ex-presidente da Caixa.<\/p>\n<p>&#8220;Foi uma delibera\u00e7\u00e3o da Caixa por uma quest\u00e3o de seguran\u00e7a do presidente da institui\u00e7\u00e3o&#8221;, disse Oliveira Lima \u00e0 Folha.<\/p>\n<p>A Caixa afirmou ao jornal que disponibiliza aparatos de seguran\u00e7a pessoal a empregados e dirigentes &#8220;expostos a situa\u00e7\u00e3o de risco quanto \u00e0 sua integridade f\u00edsica, em raz\u00e3o do exerc\u00edcio de suas atribui\u00e7\u00f5es, por meio de adequada avalia\u00e7\u00e3o do grau de criticidade envolvido e da compatibilidade do instrumental necess\u00e1rio \u00e0 preven\u00e7\u00e3o de incidentes em decorr\u00eancia desse risco&#8221;.<\/p>\n<div id=\"taboola-organic-mid-article\" class=\" trc_related_container trc_spotlight_widget trc_elastic trc_elastic_organic-Mid-Article \" data-placement-name=\"Organic Mid Article\">\n<div class=\"trc_rbox_container\">\n<div>\n<div id=\"trc_wrapper_88264\" class=\"trc_rbox organic-Mid-Article trc-content-organic \"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ad_mrec_intext2\" data-google-query-id=\"CJCMx7W08_gCFbcAuQYdDdQHCw\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/economia.ig.com.br\/mrec_2__container__\"><\/div>\n<\/div>\n<p>Em rela\u00e7\u00e3o \u00e0 internet, a Caixa informou que &#8220;dada a relev\u00e2ncia do cargo, o banco disponibiliza acesso seguro, notebook e celular corporativo \u00e0 presid\u00eancia do banco para suas atividades laborais&#8221;.<\/p>\n<p>O presidente tamb\u00e9m teria sofrido ataques hacker e, por isso, a relev\u00e2ncia de se fornecer internet.<\/p>\n<p class=\" \">Guimar\u00e3es \u00e9 investigado por \u00f3rg\u00e3o de controle tanto pelas obras em sua casa, quanto por diversas den\u00fancias de ass\u00e9dio feitas por funcion\u00e1rias do banco.<\/p>\n<p>Ele pediu demiss\u00e3o do banco no\u00a0\u00a0<a href=\"https:\/\/economia.ig.com.br\/2022-06-29\/pedro-guimaraes-presidente-caixa-demissao.html\">final de junho para cuidar de sua defesa.<\/a><\/p>\n<p>Guimar\u00e3es era bra\u00e7o direito do presidente e chegou a ser cotado para vice na chapa de Bolsonaro. As den\u00fancias, portanto, ca\u00edram como uma bomba no n\u00facleo de campanha \u00e0 reelei\u00e7\u00e3o, que busca melhorar o desempenho de Bolsonaro entre o eleitorado feminino.<\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Banco alega que medidas eram para evitar viol\u00eancia contra o ex-presidente<\/p>\n","protected":false},"author":5,"featured_media":393103,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-393102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/pedro-da-caixa.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=393102"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/393103"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=393102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=393102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=393102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}