{"id":393271,"date":"2022-07-14T05:58:08","date_gmt":"2022-07-14T08:58:08","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=393271"},"modified":"2022-07-14T05:59:39","modified_gmt":"2022-07-14T08:59:39","slug":"prefeitura-de-juazeiro-inicia-implantacao-de-nova-iluminacao-publica-no-residencial-dr-humberto-iii","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/prefeitura-de-juazeiro-inicia-implantacao-de-nova-iluminacao-publica-no-residencial-dr-humberto-iii\/","title":{"rendered":"Prefeitura de Juazeiro inicia implanta\u00e7\u00e3o de nova ilumina\u00e7\u00e3o p\u00fablica no Residencial Dr. Humberto III"},"content":{"rendered":"<p dir=\"ltr\" style=\"text-align: justify;\">Para garantir mais seguran\u00e7a para a popula\u00e7\u00e3o, a Prefeitura de Juazeiro iniciou, nesta quarta-feira (13), a implanta\u00e7\u00e3o de nova ilumina\u00e7\u00e3o p\u00fablica no Residencial Dr. Humberto III. Ser\u00e3o instalados quase 100 bra\u00e7os de ilumina\u00e7\u00e3o com novas lumin\u00e1rias na comunidade.<\/p>\n<figure id=\"attachment_393272\" aria-describedby=\"caption-attachment-393272\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-393272 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Dona-Maria-Vitoria-Melo-comemora-nova-iluminacao.jpg 1280w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-393272\" class=\"wp-caption-text\">Dona Maria Vit\u00f3ria Melo comemora nova ilumina\u00e7\u00e3o<\/figcaption><\/figure>\n<p dir=\"ltr\" style=\"text-align: justify;\">O trabalho faz parte do planejamento da Secretaria de Servi\u00e7os P\u00fablicos (Sesp), por meio do programa Disk Luz, que \u00e9 in\u00e9dito em Juazeiro e tem por objetivo manter a cidade e os distritos sempre bem iluminados, com mais agilidade no atendimento. O superintendente de Ilumina\u00e7\u00e3o, Braz Lima, junto com sua equipe, esteve na comunidade acompanhando os trabalhos.<\/p>\n<figure id=\"attachment_393273\" aria-describedby=\"caption-attachment-393273\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-393273 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III.jpg 1280w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-393273\" class=\"wp-caption-text\">Disk Luz Res Dr Humberto III<\/figcaption><\/figure>\n<p dir=\"ltr\" style=\"text-align: justify;\">O morador Afr\u00e2nio Elias acredita que a ilumina\u00e7\u00e3o vai deixar o residencial mais seguro. \u201cTem que ter ilumina\u00e7\u00e3o e claridade. Com a ilumina\u00e7\u00e3o boa vai ficar maravilhoso, com mais seguran\u00e7a. Quanto mais ilumina\u00e7\u00e3o, melhor\u201d, disse.<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-393275 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-620x349.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-768x432.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto-640x360.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/residencial-doutor-humberto.jpg 1280w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Dona Maria Vit\u00f3ria Melo compartilha do mesmo sentimento. \u201cAgora vai melhorar, com todos os postes tendo l\u00e2mpada. Com ilumina\u00e7\u00e3o boa, a gente pode sair \u00e0 noite, sem medo, e ir na casa do vizinho. A gente pode sair de casa\u201d, celebrou a moradora.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Disk Luz<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Implantado no \u00faltimo m\u00eas de fevereiro, o programa Disk Luz tem garantido atendimento com agilidade. Para isso, basta ligar para a central de atendimento, atrav\u00e9s do n\u00famero (74) 3611-1907, de segunda a sexta-feira, das 08h \u00e0s 17h. As equipes de ilumina\u00e7\u00e3o atender\u00e3o \u00e0s solicita\u00e7\u00f5es em at\u00e9 72 horas na \u00e1rea urbana, enquanto no interior o prazo \u00e9 de at\u00e9 cinco dias.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">&#8211;<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Ascom\/PMJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dona Maria Vit\u00f3ria Melo compartilha do mesmo sentimento. \u201cAgora vai melhorar, com todos os postes tendo l\u00e2mpada. Com ilumina\u00e7\u00e3o boa, a gente pode sair \u00e0 noite, sem medo, e ir na casa do vizinho. A gente pode sair de casa\u201d, celebrou a moradora.<\/p>\n","protected":false},"author":5,"featured_media":393274,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-393271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Disk-Luz-Res-Dr-Humberto-III-3.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=393271"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/393274"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=393271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=393271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=393271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}