{"id":393461,"date":"2022-07-16T08:49:00","date_gmt":"2022-07-16T11:49:00","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=393461"},"modified":"2022-07-16T08:49:00","modified_gmt":"2022-07-16T11:49:00","slug":"o-perigo-do-sexo-oral-sem-camisinha","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/o-perigo-do-sexo-oral-sem-camisinha\/","title":{"rendered":"O perigo do sexo oral sem camisinha"},"content":{"rendered":"<div class=\"box-title\">\n<div class=\"data\">Por Alexandre Brochado<\/div>\n<\/div>\n<div class=\"box-body\" data-io-article-url=\"https:\/\/www.bahianoticias.com.br\/\">\n<div class=\"text-center\">\n<div class=\"box-img\"><img decoding=\"async\" class=\"img-center img-responsive\" src=\"https:\/\/www.bahianoticias.com.br\/fotos\/saude_noticias\/29321\/IMAGEM_NOTICIA_5.jpg?checksum=1657742663\" alt=\"Sexo oral sem camisinha pode trazer riscos a sa\u00fade; entenda\" \/><\/p>\n<div class=\"img-legenda\">Foto: Freepik<\/div>\n<\/div>\n<\/div>\n<div class=\"text-descricao\">\n<p><strong>Usar preservativos durante as rela\u00e7\u00f5es sexuais \u00e9 algo muito debatido e essencial para a preven\u00e7\u00e3o de infec\u00e7\u00f5es sexualmente transmiss\u00edveis (IST), como a s\u00edfilis, a gonorreia e alguns tipos de hepatites. O que muitas pessoas n\u00e3o sabem \u00e9 que a camisinha deve ser usada para al\u00e9m da penetra\u00e7\u00e3o, sendo importante para prevenir doen\u00e7as tamb\u00e9m no sexo oral.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>A m\u00e9dica ginecologista e professora na Medicina FTC,\u00a0especialista em IST, Karen Abbehusen, explicou ao Bahia Not\u00edcias que a via oral n\u00e3o \u00e9 o principal meio de transmiss\u00e3o de infec\u00e7\u00f5es, como o sexo receptivo anal ou vaginal, quando pode ocorrer a transmiss\u00e3o com mais frequ\u00eancia. Por\u00e9m\u00a0Karen alerta que a boca \u00e9 uma via que deve ter uma aten\u00e7\u00e3o e que necessita de preocupa\u00e7\u00e3o.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cExiste sim formas de transmiss\u00e3o de ISTs no sexo oral.\u00a0Depende muito se h\u00e1 les\u00e3o na mucosa oral da pessoa que est\u00e1 fazendo o sexo oral e se tem les\u00e3o na regi\u00e3o genital da pessoa que est\u00e1 recebendo. Se tem les\u00e3o de mucosa, \u00e9 poss\u00edvel adquirir s\u00edfilis, HPV, e pode ser uma forma de transmiss\u00e3o de clam\u00eddia e Gonococos [popularmente conhecido como Gonorr\u00e9ia]. Por isso \u00e9 necess\u00e1rio o uso de camisinha no sexo oral, uma forma de preven\u00e7\u00e3o de IST\u201d, declarou a especialista.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Apesar da pessoa que faz o sexo oral estar mais exposta a adquirir uma IST, tamb\u00e9m pode acontecer da pessoa que est\u00e1 recebendo o sexo oral ser infectada caso haja alguma les\u00e3o na boca de quem est\u00e1 praticando o ato. Mas, segundo a m\u00e9dica, essa possibilidade \u00e9 mais rara. Ela, no entanto,\u00a0n\u00e3o descarta.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Entre as infec\u00e7\u00f5es sexualmente transmiss\u00edveis que podem ser adquiridas por meio do sexo oral est\u00e1 a clam\u00eddia, que pode gerar inflama\u00e7\u00e3o nos canais genitais e urin\u00e1rios, e infertilidade, al\u00e9m de, na grande maioria das vezes, ser uma doen\u00e7a silenciosa. As outras ISTs virais que muitas vezes n\u00e3o apresentam sintomas s\u00e3o hepatite e s\u00edfilis.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>No caso da s\u00edfilis, Karen cita que ela pode ser mais grave depois de um tempo de adquirida. \u201cS\u00edfilis tardia pode causar sintomas neurol\u00f3gicos e cardiol\u00f3gicos bem s\u00e9rios anos depois da aquisi\u00e7\u00e3o. De forma aguda, ela faz uma ferida indolor, que muitas vezes passa despercebida. O que tem se pautado muito \u00e9 que tem crescido a incid\u00eancia de s\u00edfilis e na gesta\u00e7\u00e3o ela preocupa, pois pode levar a morte fetal\u201d, apontou.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mesmo sendo algo mais dificil, o HIV pode ser contra\u00eddo durante do sexo oral, por\u00e9m depende da carga viral da pessoa que est\u00e1 recebendo o sexo oral. \u201cMas obrigatoriamente \u00e9 necess\u00e1rio ter uma les\u00e3o na mucosa oral para que o v\u00edrus penetre. No sexo anal ou vaginal voc\u00ea pode ter mais les\u00f5es devido ao pr\u00f3prio trauma da rela\u00e7\u00e3o e isso [a infec\u00e7\u00e3o] se torna mais f\u00e1cil. Importante lembrar que se a carga viral for indetect\u00e1vel a pessoa [que vive com HIV] n\u00e3o transmite [o v\u00edrus], e para isso ela precisa estar tratando\u201d, justifica a m\u00e9dica.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Al\u00e9m da camisinha, uma forma de se prevenir, de acordo com a ginecologista, \u00e9 estar sempre se testando. \u201cSabemos que a camisinha protege sim, ela \u00e9 bem defendida, mas n\u00e3o \u00e9 100%. Algumas situa\u00e7\u00f5es como herpes e HPV [apenas a camisinha] n\u00e3o vai ter 100% de seguran\u00e7a. Voc\u00ea est\u00e1 fazendo testagem [regularmente] &#8211; principalmente as pessoas que possuem m\u00faltiplos parceiros &#8211; \u00e9 bom estar sempre tendo esse cuidado\u201d, destaca a especialista.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Karen menciona ainda que a Profilaxia Pr\u00e9-Exposi\u00e7\u00e3o (PrEP) \u00e9 um importante meio de preven\u00e7\u00e3o contra o HIV, mas quem faz o uso tamb\u00e9m precisa fazer um acompanhamento bem rigoroso, at\u00e9 para estar atento a ISTs que muitas vezes s\u00e3o assintom\u00e1ticas.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cAcredito que os jovens, antes de iniciar a vida sexual, tenham uma educa\u00e7\u00e3o para o sexo seguro, sobre uso de preservativo, para assim estarem se preservando nesse sentindo. Tamb\u00e9m \u00e9 importante estarem se testando e se vacinarem contra as doen\u00e7as que possuem vacina, como o HPV, que est\u00e1 bem abaixo do \u00edndice de vacina\u00e7\u00e3o da popula\u00e7\u00e3o, e n\u00f3s temos a vacina dispon\u00edvel por meio do SUS (Sistema \u00danico de Sa\u00fade). Tenho visto que o pessoal est\u00e1 deixando muito de ter medo do HIV, hoje gra\u00e7as a Deus n\u00e3o temos muitos \u00f3bitos, mas \u00e9 uma doen\u00e7a cr\u00f4nica que vai exigir tratamento para o resto da vida, ent\u00e3o prevenir \u00e9 melhor\u201d, alertou a especialista. (BN)<\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Alexandre Brochado Foto: Freepik Usar preservativos durante as rela\u00e7\u00f5es sexuais \u00e9 algo muito debatido e essencial para a preven\u00e7\u00e3o de infec\u00e7\u00f5es sexualmente transmiss\u00edveis (IST), como a s\u00edfilis, a gonorreia e alguns tipos de hepatites. O que muitas pessoas n\u00e3o sabem \u00e9 que a camisinha deve ser usada para al\u00e9m da penetra\u00e7\u00e3o, sendo importante para [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":327809,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-393461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2020\/08\/sexo-pes.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=393461"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/327809"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=393461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=393461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=393461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}