{"id":393988,"date":"2022-07-21T11:02:35","date_gmt":"2022-07-21T14:02:35","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=393988"},"modified":"2022-07-21T11:02:35","modified_gmt":"2022-07-21T14:02:35","slug":"equipe-de-marilia-mendonca-anuncia-lancamento-de-ep","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/equipe-de-marilia-mendonca-anuncia-lancamento-de-ep\/","title":{"rendered":"Equipe de Mar\u00edlia Mendon\u00e7a anuncia lan\u00e7amento de EP"},"content":{"rendered":"<div class=\"col-sm-12 ig-container_headerText\">\n<h1 id=\"noticia-titulo-h1\" class=\"noticia-titulo-h1-ig_V04\"><\/h1>\n<h2 id=\"noticia-olho\">&#8216;Os desejos da rainha continuar\u00e3o sendo atendidos&#8217;, diz postagem sobre o projeto que chega \u00e0s plataformas nesta quinta-feira (20)<\/h2>\n<\/div>\n<div id=\"ad_billboard\" class=\"betOrBillboard\" data-google-query-id=\"CKXI9Z-SivkCFYoDuQYdhqYPbw\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/gente.ig.com.br\/billboard_0__container__\"><\/div>\n<\/div>\n<div id=\"noticia-other\" class=\"noticia-other-ig_V04\">\n<div class=\"author-container\">\n<p>Por\u00a0<strong>O Dia<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"contentNoticia\">\n<div class=\"main-content\">\n<div class=\"row\">\n<section class=\"noticia col-sm-12 plf-0\">\n<div id=\"noticia\">\n<div class=\"Noticia_Foto\">\n<figure class=\"foto-legenda \">\n<div class=\"foto-legenda-img\">\n<div id=\"standard_1\" class=\"st-placement standard_1 inImage\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\"><\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Mar\u00edlia Mendon\u00e7a faz hist\u00f3ria e alcan\u00e7a 8 bilh\u00f5es de plays no Spotify\" src=\"https:\/\/i0.statig.com.br\/bancodeimagens\/4y\/yq\/9m\/4yyq9myjgy5jlla9t233p1v96.jpg\" alt=\"Mar\u00edlia Mendon\u00e7a faz hist\u00f3ria e alcan\u00e7a 8 bilh\u00f5es de plays no Spotify\" width=\"906\" height=\"509\" \/><\/div><figcaption class=\"foto-legenda-citacao \"><cite>Marcelo de Assis<\/cite><\/p>\n<div class=\"foto-legenda-citacao-text\" data-gtm-vis-recent-on-screen-214867_1952=\"4340\" data-gtm-vis-first-on-screen-214867_1952=\"4340\" data-gtm-vis-total-visible-time-214867_1952=\"100\" data-gtm-vis-has-fired-214867_1952=\"1\">Mar\u00edlia Mendon\u00e7a faz hist\u00f3ria e alcan\u00e7a 8 bilh\u00f5es de plays no Spotify<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\"   \">\n<p>Rio &#8211; Os f\u00e3s de Mar\u00edlia Mendon\u00e7a ficaram animados com novidades que a equipe da artista prepara oito meses ap\u00f3s a morte da cantora em um acidente tr\u00e1gico de avi\u00e3o. \u00c9 que o primeiro projeto p\u00f3stumo da sertaneja ser\u00e1 lan\u00e7ado na noite desta quinta-feira, o EP intitulado &#8220;Decretos Reais&#8221;. O lan\u00e7amento acontece na v\u00e9spera do dia em que a artista completaria 27 anos de idade.<\/p>\n<p>Nesta quarta-feira, internautas perceberam a altera\u00e7\u00e3o da foto de perfil nas contas de Mar\u00edlia no Twitter e no Instagram. &#8220;Os desejos da rainha continuar\u00e3o sendo atendidos&#8221;, diz uma das imagens utilizadas. Pouco depois, a equipe da cantora divulgou uma postagem enigm\u00e1tica, dando dicas sobre os projetos futuros.<\/p>\n<p class=\"\">\n<p>&#8220;\u00c0 tona vieram os decretos, os desejos e os sonhos da Rainha eleita pelo povo. A coroa intransfer\u00edvel, brilha como sempre em n\u00f3s, eternos s\u00faditos, estamos encarregados de assegurar o cumpra-se. Amanh\u00e3 \u00e0s 21h&#8221;, dizia a legenda de um v\u00eddeo. No registro, \u00e9 mostrado um pergaminho que acrescentou:\u00a0&#8220;A partir de 20\/07\/2022, todos ser\u00e3o contemplados com uma s\u00e9rie de presentes e acontecimentos em mem\u00f3ria de Mar\u00edlia Mendon\u00e7a e seu legado real&#8221;.<br \/>\n\u00c0 tona vieram os decretos, os desejos e os sonhos da \u00fanica Rainha eleita pelo povo. A coroa intransfer\u00edvel, brilha como sempre em n\u00f3s, eternos s\u00faditos, estamos encarregados de assegurar o cumpra-se.<\/p>\n<div id=\"taboola-organic-mid-article\" class=\" trc_related_container trc_spotlight_widget trc_elastic trc_elastic_organic-Mid-Article \" data-placement-name=\"Organic Mid Article\">\n<div class=\"trc_rbox_container\">\n<div>\n<div id=\"trc_wrapper_50945\" class=\"trc_rbox organic-Mid-Article trc-content-organic \"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ad_mrec_intext2\" data-google-query-id=\"CLvz-Z-SivkCFYoDuQYdhqYPbw\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/gente.ig.com.br\/mrec_2__container__\"><\/div>\n<\/div>\n<p>Os detalhes sobre o novo projeto foram divulgados pela assessoria da cantora em nota enviada ao\u00a0DIA,\u00a0revelando as novidades que est\u00e3o entre os &#8220;Decretos Reais&#8221; deixados pela artista. Al\u00e9m de confirmar o lan\u00e7amento do EP nesta quinta-feira, o comunicado ainda explica que o compacto incluir\u00e1 quatro faixas retiradas da live &#8220;Serenata&#8221;, realizada pela sertaneja em maio do ano passado.<\/p>\n<p>Al\u00e9m disso, o canal de dona Ruth Moreira, m\u00e3e de Mar\u00edlia, disponibilizar\u00e1 o v\u00eddeo de uma reuni\u00e3o entre grandes nomes do sertanejo que se juntaram para homenagear a dona do sucesso &#8220;Troca de Cal\u00e7ada&#8221;. No registro, o irm\u00e3o da cantora, Jo\u00e3o Gustavo, e seu parceiro Dom Vitor, se re\u00fane com Murilo Huff, Henrique Casttro, Luiza (da dupla com o falecido Maur\u00edlio) e as duplas Hugo e Guilherme, Maiara e Maraisa, Vitor e Luan.<\/p>\n<p>&#8220;Mar\u00edlia partiu, mas deixou uma lista de &#8216;vontades&#8217;, que intitulamos como &#8216;Decretos Reais&#8217; para serem cumpridos ao longo do ano. Os primeiros est\u00e3o a\u00ed, manter seus lan\u00e7amentos e sua voz ao alcance de todos e ver a m\u00e3e com seu pr\u00f3prio espa\u00e7o&#8221;, destaca a assessoria de Mar\u00edlia, adiantando que ainda tem muito mais a caminho.<\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Os desejos da rainha continuar\u00e3o sendo atendidos&#8217;, diz postagem sobre o projeto que chega \u00e0s plataformas nesta quinta-feira (20)<\/p>\n","protected":false},"author":5,"featured_media":371481,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-393988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/11\/marilia-mendonca-em-petrolina.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=393988"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/393988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/371481"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=393988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=393988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=393988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}