{"id":394445,"date":"2022-07-26T17:00:48","date_gmt":"2022-07-26T20:00:48","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=394445"},"modified":"2022-07-26T17:00:48","modified_gmt":"2022-07-26T20:00:48","slug":"roma-provoca-neto-quem-tem-mania-de-desistir-e-outro-que-sempre-amarela","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/roma-provoca-neto-quem-tem-mania-de-desistir-e-outro-que-sempre-amarela\/","title":{"rendered":"Roma provoca Neto: \u2018Quem tem mania de desistir \u00e9 outro que sempre amarela\u2019"},"content":{"rendered":"<h1><\/h1>\n<h2>Ele refor\u00e7ou a sua candidatura ao governo baiano e ressaltou que n\u00e3o costuma desistir de disputar pleitos eletivos<\/h2>\n<div class=\"autor\">Reda\u00e7\u00e3o<\/div>\n<div id=\"div-share\"><\/div>\n<div class=\"materia\">\n<div class=\"conteudo_post\">\n<figure id=\"attachment_324750\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/07\/26123543\/Jo%C3%A3o-Roma-Metr%C3%B3pole.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-324750 size-full\" src=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/07\/26123543\/Jo%C3%A3o-Roma-Metr%C3%B3pole.png\" alt=\"Foto: assessoria\/Jo\u00e3o Roma\" width=\"600\" height=\"420\" \/><\/a><figcaption class=\"wp-caption-text\">Foto: assessoria\/Jo\u00e3o Roma<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>O candidato a governador da Bahia, ex-ministro da Cidadania e deputado federal, Jo\u00e3o Roma (PL), reafirmou a firmeza de sua candidatura e ressaltou n\u00e3o ser ele quem costuma desistir de disputar pleitos eletivos, numa cr\u00edtica ao ex-prefeito de Salvador, ACM Neto (UB). \u201cQuem tem mania de desistir \u00e9 o outro que sempre amarela\u201d, provocou Roma, que voltou a dizer que sua candidatura representa um diferencial em rela\u00e7\u00e3o a ACM Neto e a Jer\u00f4nimo Rodrigues, do PT, que t\u00eam como marca a m\u00e3o pesada para cobrar impostos.<\/p>\n<p>A declara\u00e7\u00e3o do ex-ministro da Cidadania ocorreu em entrevista \u00e0 R\u00e1dio Metr\u00f3pole, na manh\u00e3 desta ter\u00e7a-feira (26). \u201cEu estou movido por um prop\u00f3sito muito claro. O que est\u00e1 nos motivando n\u00e3o \u00e9 o desejo de ocupar um cargo, mas realmente ser porta-voz do povo baiano e para mostrar uma Bahia grandiosa, mas que tem ficado para tr\u00e1s em rela\u00e7\u00e3o a outros estados\u201d, disse Roma, que pontuou que o estado tem perdido competitividade e investimentos.<\/p>\n<p>Sobre a composi\u00e7\u00e3o de sua chapa, Roma declarou: \u201cbusquei realmente encontrar pessoas que estejam movidas com o mesmo prop\u00f3sito\u201d. A chapa apoiada pelo presidente Jair Bolsonaro (PL) na Bahia \u00e9 formada dor duas mulheres, Doutora Ra\u00edssa Soares (PL), candidata ao Senado, e Leon\u00eddia Umbelina (PMB), candidata a vice-governadora. \u201cResolvi, sim, dar oportunidade porque muitos gostam de dizer que \u00e9 importante a participa\u00e7\u00e3o da mulher da pol\u00edtica, mas poucos d\u00e3o oportunidade para que a mulher participe da pol\u00edtica\u201d, destacou Roma.<\/p>\n<p>O candidato do PL ao governo tamb\u00e9m realizou uma defesa enf\u00e1tica do aperfei\u00e7oamento do processo eleitoral brasileiro e criticou a posi\u00e7\u00e3o de ministros de cortes superiores brasileiras que n\u00e3o aceitam debater o tema. \u201cEu s\u00f3 acho esquisito \u00e9 que quem cuida da urna eletr\u00f4nica \u00e9 t\u00e3o reativo ao tema, pois tudo tem que ser aperfei\u00e7oado na vida. Eu acho que a urna eletr\u00f4nica veio pra aperfei\u00e7oar o processo\u201d, disse Roma, que tamb\u00e9m rebateu a narrativa falsa segundo a qual o presidente Jair Bolsonaro deseja o retorno do voto em c\u00e9dulas de papel.<\/p>\n<p>\u201cEle [Bolsonaro] prop\u00f4s aferi\u00e7\u00e3o. O que que era isso? Um inv\u00f3lucro de acr\u00edlico onde voc\u00ea votaria e voc\u00ea iria ver o extrato de seu voto. Ningu\u00e9m iria sair com o papelzinho na m\u00e3o, nem iria pegar em papel. Isso era o qu\u00ea? Era mais um caminho para aferir como \u00e9 em Portugal, por exemplo\u201d, exemplificou o candidato a governador.<\/p>\n<p>Jo\u00e3o Roma tamb\u00e9m criticou o ativismo judicial de membros das cortes superiores como o ministro do STF [Supremo Tribunal Federal] e do TSE [Tribunal Superior Eleitoral], Alexandre de Moraes. \u201cV\u00ea o que Alexandre de Moraes est\u00e1 fazendo? O nome disso n\u00e3o \u00e9 ativismo judicial? Ele usa dois pesos e duas medidas. Ele executa, ele julga, ele denuncia. Ent\u00e3o isso n\u00e3o \u00e9 o caminho da lei. Ent\u00e3o o que n\u00f3s queremos? Transpar\u00eancia no processo\u201d, refor\u00e7ou Roma.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ele refor\u00e7ou a sua candidatura ao governo baiano e ressaltou que n\u00e3o costuma desistir de disputar pleitos eletivos<\/p>\n","protected":false},"author":5,"featured_media":394446,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-394445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/Joao-Roma-Metropole.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=394445"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/394446"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=394445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=394445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=394445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}