{"id":394640,"date":"2022-07-29T08:06:43","date_gmt":"2022-07-29T11:06:43","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=394640"},"modified":"2022-07-29T08:06:43","modified_gmt":"2022-07-29T11:06:43","slug":"juazeiro-petrolina-gonzagueanos-mantem-legado-de-luiz-gonzaga-vivo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/juazeiro-petrolina-gonzagueanos-mantem-legado-de-luiz-gonzaga-vivo\/","title":{"rendered":"Juazeiro\/Petrolina: Gonzagueanos mant\u00e9m legado de Luiz Gonzaga vivo"},"content":{"rendered":"<div style=\"text-align: justify;\">Por: Ney Vital<\/div>\n<p style=\"text-align: justify;\">Em 1989, ano da morte de Luiz Gonzaga, Diego Silva de Andrade era um uma crian\u00e7a de 4 anos. Nascido no Distrito de Pilar, Cara\u00edbas Metais, \u00a0o hoje empres\u00e1rio vai completar 37 anos. Herdou do seu saudoso pai o gosto pela m\u00fasica de Luiz Gonzaga.Adolescente adquiriu o h\u00e1bito de gravar programas de r\u00e1dios dedicados \u00e0 vida e obra de Luiz Gonzaga.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-394641 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga.jpg\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga.jpg 700w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-300x300.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-500x500.jpg 500w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-150x150.jpg 150w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-160x160.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-640x640.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-30x30.jpg 30w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga-266x266.jpg 266w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Diego \u00e9 um dos gonzagueanos que todos os anos, na data do nascimento de Luiz Gonzaga, 13 dezembro, \u00e9 presen\u00e7a na festa do Rei do Bai\u00e3o.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Ele coleciona um acervo de discos raros de Luiz Gonzaga. S\u00e3o lps, alguns rar\u00edssimos, em formato de cera e revistas. Diego possui um grande n\u00famero de fotos com os nomes mais renomados da m\u00fasica brasileira, exemplo Gilberto Gil e Dominguinhos. O amor pela obra de Luiz Gonzaga despertou em Diego a vontade de aprender a tocar sanfona.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>&#8220;Um dos momentos mais fortes e emocionantes foi participar em 2012 dos 100 anos de nascimento de Luiz Gonzaga l\u00e1 em Exu, terra onde ele nasceu. Marcou a minha vida&#8221;, relata Diego. Recentemente Diego esteve realizando uma visita ao compositor Onildo Almeida que vive em Caruaru, agreste de Pernambuco, um dos mais talentosos parceiros do Rei do Bai\u00e3o.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Outro momento especial, de acordo com Diego, foi fazer o anivers\u00e1rio tem\u00e1tico para festejar o anivers\u00e1rio do seu primeiro filho, de 3 anos, com o tema sobre Luiz Gonzaga. &#8220;\u00c9 natural buscarmos transmitir para as novas gera\u00e7\u00f5es o valor e import\u00e2ncia de Luiz Gonzaga para a cultura brasileira&#8221;, diz Diego.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Luiz Gonzaga (1912 &#8211; 1989) \u00e9 um dos principais nomes da hist\u00f3ria da m\u00fasica brasileira, completar\u00e1 110 anos em dezembro. E, para comemorar a data, Paulo Vanderley, que desenvolve pesquisas sobre a vida e a obra do artista, iniciou uma s\u00e9rie de a\u00e7\u00f5es. Uma destas atividades \u00e9 o podcast \u201cLuiz Gonzaga &#8211; 110 anos do Nascimento\u201d, que est\u00e1 dispon\u00edvel nas plataformas de streaming Spotify e Anchor.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Os epis\u00f3dios j\u00e1 podem ser escutados toda quarta-feira. Diego Andrade \u00e9 um dos participantes do Podcast. Paulo Vanderley diz que o objetivo do programa durante o ano \u00e9 dialogar com pessoas pr\u00f3ximas do artista e de seu trabalho. Nos conte\u00fados j\u00e1 houve conversas com Lenine, F\u00e1bio Passadisco, Breno Silveira e Chambinho.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Em Juazeiro, para homenagear Luiz Gonzaga, existe um grupo de pessoas, que se dedica a estudar a vida e obra de Luiz Gonzaga. O Bloco O Gonzag\u00e3o foi idealizado em 1996, portanto s\u00e3o 26 anos valorizando e preservando a mem\u00f3ria do sanfoneiro Luiz Gonzaga. Neste dia 02 de agosto de 2018, o Grupo mais uma vez presta homenagens ao Rei do Bai\u00e3o. Sanfoneiros e pesquisadores formaram uma roda de sanfona para celebrar a aus\u00eancia f\u00edsica do sanfoneiro do Riacho da Br\u00edgida.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>O presidente do Bloco O Gonzag\u00e3o, Jo\u00e3o Luiz, diz que \u00e9 tradi\u00e7\u00e3o todo ano, \u00a0dia 02 de agosto, a festa da saudade e no dia do nascimento especial 13 de dezembro, o grupo se unir e participar da Missa de A\u00e7\u00e3o de Gra\u00e7as em Exu. \u00a0&#8220;Ouvimos m\u00fasica, uns trazem discos vinil antigo, at\u00e9 fita cassete, outros j\u00e1 mostram a tecnologia mais avan\u00e7ada que tem destaque Luiz Gonzaga. E assim mantemos viva a hist\u00f3ria de Luiz Gonzaga&#8221;.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>No espa\u00e7o, localizado no bairro Jo\u00e3o XXIII em Juazeiro, onde funciona o ponto de Encontro dos Gonzagueanos, existe uma exposi\u00e7\u00e3o de quadros da vida e obra de Luiz Gonzaga e toda uma gastronomia nordestina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diego \u00e9 um dos gonzagueanos que todos os anos, na data do nascimento de Luiz Gonzaga, 13 dezembro, \u00e9 presen\u00e7a na festa do Rei do Bai\u00e3o.<\/p>\n<p>Ele coleciona um acervo de discos raros de Luiz Gonzaga. S\u00e3o lps, alguns rar\u00edssimos, em formato de cera e revistas. Diego possui um grande n\u00famero de fo<\/p>\n","protected":false},"author":5,"featured_media":394641,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-394640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/gil-e-gonzaga.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=394640"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/394641"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=394640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=394640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=394640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}