{"id":394811,"date":"2022-07-31T18:34:23","date_gmt":"2022-07-31T21:34:23","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=394811"},"modified":"2022-07-31T18:34:23","modified_gmt":"2022-07-31T21:34:23","slug":"james-lovelock-morto-aos-103-anos-elaborou-hipotese-de-que-terra-funciona-como-organismo-vivo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/james-lovelock-morto-aos-103-anos-elaborou-hipotese-de-que-terra-funciona-como-organismo-vivo\/","title":{"rendered":"James Lovelock, morto aos 103 anos, elaborou hip\u00f3tese de que Terra funciona como organismo vivo"},"content":{"rendered":"<div class=\"row content-head featured \">\n<div class=\"title\">\n<h1 class=\"content-head__title\" style=\"text-align: justify;\"><\/h1>\n<\/div>\n<div class=\"medium-centered subtitle\" style=\"text-align: justify;\">\n<h2 class=\"content-head__subtitle\">Cientista e ambientalista influente, autor da teoria de Gaia passava por complica\u00e7\u00f5es de sa\u00fade ap\u00f3s ter sofrido uma queda em sua resid\u00eancia<\/h2>\n<\/div>\n<\/div>\n<div class=\"content__signa-share\" style=\"text-align: justify;\">\n<div class=\"content__signature\">\n<div class=\"content-publication-data\">\n<div class=\"content-publication-data__text\">\n<p class=\"content-publication-data__from\" title=\"Rafael Garcia\">Por Rafael Garcia<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content__share-bar\"><\/div>\n<\/div>\n<div class=\"row medium-uncollapsed content-top-image\" style=\"text-align: justify;\" data-block-type=\"featured-image\" data-block-id=\"0\">\n<div class=\"column medium-centered medium-22 large-20 desktop \">\n<figure class=\"glb-skeleton-box\"><img decoding=\"async\" class=\"i-amphtml-fill-content i-amphtml-replaced-content\" src=\"https:\/\/s2.glbimg.com\/gt2kCU9v4q_xb9ulvc2Jxas4--Y=\/0x0:720x480\/924x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_da025474c0c44edd99332dddb09cabe8\/internal_photos\/bs\/2022\/v\/t\/RsmNxBRASrUG9EfKEDGA\/36074561-ch-rio-de-janeiro-rj-13-01-2010-james-lovelock.-foto-divulgacao.jpg\" srcset=\"\" alt=\"James Lovelock, morto aos 103 anos, elaborou hip\u00f3tese de que Terra funciona como organismo vivo\" \/><\/figure>\n<p><span class=\"name\">James Lovelock, em foto de 2010<\/span>\u00a0<span class=\"rights-holder\">Reprodu\u00e7\u00e3o<\/span><\/div>\n<\/div>\n<div class=\"mc-article-body\">\n<article>\n<div class=\"mc-column mc-side-item__container\" style=\"text-align: justify;\" data-block-type=\"ads\" data-block-id=\"1\">\n<div class=\"mc-side-item mc-side-item--right content-ads content-ads--side-ad\">\n<div id=\"banner_materia1\" class=\"tag-manager-publicidade-container tag-manager-publicidade-banner_materia1 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-google-query-id=\"CKfb9K6JpPkCFf44uQYdvowLAQ\" data-cid=\"138398404188\" data-lid=\"6066180943\">\n<div id=\"google_ads_iframe_85042905\/info.web.oglobo\/mundo\/materia_0__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles active-capital-letter\" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"58\" data-block-id=\"2\">\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">Morreu na manh\u00e3 desta ter\u00e7a-feira, aos 103 anos, o cientista brit\u00e2nico James Lovelock, criador da Teoria de Gaia, segundo a qual a Terra funciona como um organismo vivo. Autor influente entre ambientalistas e ec\u00f3logos nas d\u00e9cadas de 1970 e 1980, ele passava por complica\u00e7\u00f5es de sa\u00fade ap\u00f3s ter sofrido uma queda em sua resid\u00eancia, em Dorset, na Inglaterra.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"55\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No meio cient\u00edfico, Lovelock foi sempre uma figura controversa, mas que provocou reflex\u00f5es importantes. A Teoria de Gaia (batizada com o nome da deusa grega que representa a Terra) postulava que o planeta como um todo possui uma esp\u00e9cie de consci\u00eancia pr\u00f3pria, um mecanismo org\u00e2nico de autorregula\u00e7\u00e3o que atua para criar condi\u00e7\u00f5es para a vida.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"58\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Por seu apelo m\u00edstico, a hip\u00f3tese atraiu inicialmente muitos adeptos do movimento Nova Era, que ajudaram a impulsionar a milit\u00e2ncia ambientalista no fim do s\u00e9culo XX. No meio acad\u00eamico, por\u00e9m, at\u00e9 hoje a hip\u00f3tese de Gaia enfrenta obst\u00e1culos, por ser considerada uma abordagem falha para a quest\u00e3o do ponto de vista filos\u00f3fico, atribuindo inten\u00e7\u00e3o a fen\u00f4menos da natureza.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"61\" data-block-id=\"7\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O debate que a teoria provocou, por\u00e9m, ajudou a consolidar a ideia de que existem de fato alguns mecanismos de autorregula\u00e7\u00e3o no planeta, alguns deles desencadeados atualmente pela mudan\u00e7a clim\u00e1tica. No meio ambientalista, Lovelock, que \u00e9 formado em medicina, \u00e9 um dos grandes respons\u00e1veis pela ideia mais bem aceita de que a Terra pune os humanos quando estes destroem os ecossistemas.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"43\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A Teoria de Gaia, criada na d\u00e9cada de 1960, ganhou muita popularidade a partir da d\u00e9cada seguinte, ap\u00f3s a bi\u00f3loga Lynn Margulis ajud\u00e1-lo a desdobrar e modernizar sua ideia. Ap\u00f3s os anos 2000, uma forma menos esot\u00e9rica da hip\u00f3tese aumentou sua aceita\u00e7\u00e3o acad\u00eamica.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"39\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No Brasil, um dos cientistas inspirados pelo mecanismo de Gaia \u00e9 Antonio Nobre, pioneiro no estudo do transporte de umidade da Amaz\u00f4nia que ajuda a sustentar outros biomas do continente. Sua ideia ficou conhecida como teoria dos &#8220;rios voadores&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"63\" data-block-id=\"11\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A despeito da notoriedade que Lovelock ganhou ao longo das d\u00e9cadas, algumas de suas posi\u00e7\u00f5es \u2014 particularmente a defesa das usinas nucleares \u2014 o colocaram em conflito com a comunidade ambientalista. Por ser uma fonte de energia que n\u00e3o emite CO2, ele acreditava que a energia at\u00f4mica merecia um papel maior no combate ao aquecimento global, a despeito de outros risco que oferecia.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"43\" data-block-id=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Tamb\u00e9m foi alvo de cr\u00edticas a sua defesa da contracep\u00e7\u00e3o como forma de combate \u00e0 mudan\u00e7a clim\u00e1tica, para que a redu\u00e7\u00e3o do crescimento populacional freasse a demanda por combust\u00edveis f\u00f3sseis no planeta. A declara\u00e7\u00e3o n\u00e3o foi bem recebida por ativistas dos direitos reprodutivos.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"52\" data-block-id=\"13\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O legado que James Lovelock deixa, por\u00e9m, vai al\u00e9m da elabora\u00e7\u00e3o da Teoria de Gaia e da voca\u00e7\u00e3o para o pol\u00eamico. O cientista teve importantes trabalhos em infectologia, particularmente sobre a transmiss\u00e3o do v\u00edrus da gripe. Foi tamb\u00e9m pioneiro de estudos sobre criogenia, a preserva\u00e7\u00e3o de organismos vivos por meio do congelamento.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"33\" data-block-id=\"16\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Um dispositivo que o cientista inventou (um detector de mol\u00e9culas por captura de el\u00e9trons) foi uma ferramenta importante na d\u00e9cada de 1960 para estudo dos clorofluorcarbonos, gases que danificam a camada de oz\u00f4nio.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"27\" data-block-id=\"17\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No imagin\u00e1rio p\u00fablico, Lovelock tamb\u00e9m deixa um legado importante, por ter contribu\u00eddo para a ideia de que os humanos n\u00e3o s\u00e3o um elemento apartado da natureza.<\/p>\n<\/div>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"96\" data-block-id=\"18\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;N\u00f3s somos a elite inteligente da vida animal na Terra, e quaisquer que sejam nossos erros, a Terra precisa de n\u00f3s. Esta pode parecer uma afirma\u00e7\u00e3o estranha depois de eu ter dito que os humanos se tornaram um organismo patog\u00eanico para o planeta no s\u00e9culo XX&#8221;, escreveu o cientista em seu livro &#8220;The Vanishing Face of Gaia&#8221; (A face ef\u00eamera de Gaia), de 2009. &#8220;Mas a Terra levou 2,5 bilh\u00f5es de anos para evoluir um animal capaz de pensar e comunicar seus pensamentos. Se n\u00f3s nos extinguirmos, ela tem poucas chances de evoluir outra esp\u00e9cie dessas.&#8221;<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Fonte: O Globo<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cientista e ambientalista influente, autor da teoria de Gaia passava por complica\u00e7\u00f5es de sa\u00fade ap\u00f3s ter sofrido uma queda em sua resid\u00eancia<\/p>\n","protected":false},"author":5,"featured_media":394812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,7,11],"tags":[],"class_list":["post-394811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-nacional","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/lover-lok.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=394811"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/394812"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=394811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=394811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=394811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}