{"id":394972,"date":"2022-08-02T09:21:03","date_gmt":"2022-08-02T12:21:03","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=394972"},"modified":"2022-08-02T09:21:03","modified_gmt":"2022-08-02T12:21:03","slug":"bolsonarista-que-matou-petista-nao-lembra-do-crime-diz-advogado","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/bolsonarista-que-matou-petista-nao-lembra-do-crime-diz-advogado\/","title":{"rendered":"Bolsonarista que matou petista n\u00e3o lembra do crime, diz advogado"},"content":{"rendered":"<section class=\"mw-article-head\">\n<h1 class=\"mw-h1-1 mw-default-blue\"><\/h1>\n<h2 class=\"mw-h2-1 mw-default-gray\">Policial penal matou com disparos de arma de fogo o guarda municipal que comemorava anivers\u00e1rio de 50 anos<\/h2>\n<div class=\"mw-article-head-inner\">\n<div class=\"mw-article-head-info\"><span class=\"mw-article-data mw-default-gray\"><abbr title=\"mw-article-date\"><strong>Por: <\/strong><\/abbr><abbr title=\"mw-article-author\"><strong>Reda\u00e7\u00e3o<\/strong><\/abbr><\/span><\/p>\n<div><\/div>\n<\/div>\n<figure class=\"mw-article-head-image\" data-article-id=\"1202157\"><img decoding=\"async\" src=\"https:\/\/cdn.atarde.com.br\/img\/Artigo-Destaque\/1200000\/Artigo-Destaque_01202157_00.jpg?xid=5512222\" alt=\"Jorge Jos\u00e9 da Rocha Guaranho est\u00e1 internado no Hospital Ministro Costa Cavalcanti\" data-cls=\"\" \/><\/figure>\n<div class=\"mw-image-info\"><span class=\"mw-image-description\">Jorge Jos\u00e9 da Rocha Guaranho est\u00e1 internado no Hospital Ministro Costa Cavalcanti &#8211;\u00a0<label class=\"mw-image-author\">Foto: Reprodu\u00e7\u00e3o<\/label><\/span><\/div>\n<\/div>\n<\/section>\n<section class=\"mw-article-body\">\n<article data-article-id=\"1202157\">\n<p class=\"mw-texto\">\n<p>Internado em recupera\u00e7\u00e3o,\u00a0<a href=\"https:\/\/atarde.com.br\/brasil\/justica-acata-denuncia-e-bolsonarista-vira-reu-por-morte-de-petista-1201139\" target=\"_blank\" rel=\"noopener\">o policial penal Jorge Jos\u00e9 da Rocha Guaranho<\/a>, segundo seu advogado, n\u00e3o lembra do dia em que\u00a0<a href=\"https:\/\/atarde.com.br\/brasil\/petista-e-morto-por-bolsonarista-enquanto-comemorava-aniversario-1200263\" target=\"_blank\" rel=\"noopener\">matou o guarda municipal Marcelo Arruda<\/a>, em Foz do Igua\u00e7u no dia 9 de julho.<\/p>\n<p>Luciano Santoro, que tamb\u00e9m \u00e9 advogado de\u00a0<a href=\"https:\/\/atarde.com.br\/brasil\/justica-paulista-concede-liberdade-condicional-a-elize-matsunaga-1196693\" target=\"_blank\" rel=\"noopener\">Elize Matsunaga<\/a>, assumiu a defesa de Guaranho e o visitou no Hospital Ministro Costa Cavalcanti. A alega\u00e7\u00e3o de Santoro \u00e9 que os chutes na cabe\u00e7a sofridos por Guaranho, ap\u00f3s receber o revide de Arruda, podem ter afetado sua mem\u00f3ria. \u201c\u00c9 um milagre ele ter sobrevivido. Acredito que a recupera\u00e7\u00e3o ser\u00e1 muito longa e dif\u00edcil\u201d, relata o advogado ao portal Uol.<\/p>\n<p><b>O caso<\/b><\/p>\n<p>Marcelo Arruda foi assassinado a tiros durante sua festa de anivers\u00e1rio de 50 anos, na noite de 9 de julho. A festa tinha como tema o PT e fazia v\u00e1rias refer\u00eancias ao ex-presidente Luiz In\u00e1cio Lula da Silva.<\/p>\n<p>Por volta das 23h, Jorge Guaranho, que se declara apoiador do presidente Jair Bolsonaro (PL), foi ao local e discutiu com os participantes. Ele levava no carro a esposa e a filha, um beb\u00ea de colo. Ap\u00f3s a primeira briga, Guaranho saiu, dizendo que voltaria. Minutos depois, voltou sozinho e armado e atirou em Marcelo, que revidou.<\/p>\n<\/article>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Luciano Santoro, que tamb\u00e9m \u00e9 advogado de\u00a0Elize Matsunaga, assumiu a defesa de Guaranho e o visitou no Hospital Ministro Costa Cavalcanti. A alega\u00e7\u00e3o de Santoro \u00e9 que os chutes na cabe\u00e7a sofridos por Guaranho, ap\u00f3s receber o revide de Arruda, podem ter afetado sua mem\u00f3ria. \u201c\u00c9 um milagre ele ter sobrevivido. Acredito que a recupera\u00e7\u00e3o ser\u00e1 muito longa e dif\u00edcil\u201d, relata<\/p>\n","protected":false},"author":5,"featured_media":394973,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-394972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/assassino-de-petista.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=394972"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/394972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/394973"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=394972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=394972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=394972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}