{"id":395253,"date":"2022-08-05T08:40:25","date_gmt":"2022-08-05T11:40:25","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=395253"},"modified":"2022-08-05T08:40:25","modified_gmt":"2022-08-05T11:40:25","slug":"agrovale-comemora-50-anos-e-promove-corrida-com-r-12-mil-em-premios","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/agrovale-comemora-50-anos-e-promove-corrida-com-r-12-mil-em-premios\/","title":{"rendered":"Agrovale comemora 50 anos e promove corrida com R$ 12 mil em pr\u00eamios"},"content":{"rendered":"<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\" align=\"center\">\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\"><span class=\"x_x_ContentPasted4\">J\u00e1 est\u00e3o abertas as inscri\u00e7\u00f5es para a I Corrida Agrovale, que vai premiar os 5 primeiros lugares com R$ 12 mil no pr\u00f3ximo dia 18 de setembro. A prova, em homenagem aos 50 anos da empresa sucroenerg\u00e9tica, \u00e9 destinada \u00e0s categorias Funcion\u00e1rio e Geral nas dist\u00e2ncias de 10 e 5 quil\u00f4metros.\u00a0<\/span><\/p>\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-395254 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/corrida-agrovale.jpg\" alt=\"\" width=\"319\" height=\"452\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/corrida-agrovale.jpg 319w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/corrida-agrovale-212x300.jpg 212w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/corrida-agrovale-160x227.jpg 160w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><\/p>\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\"><span class=\"x_x_ContentPasted4\">Com o percurso nas depend\u00eancias da pr\u00f3pria empresa, a prova vai come\u00e7ar \u00e0s 7h30, e poder\u00e3o participar atletas de ambos os sexos e idade igual ou superior a 14 anos. Os participantes ir\u00e3o receber um kit de corrida, composto por uma sacola (a definir), camiseta de poliamida, chip da cronometragem e n\u00famero de identifica\u00e7\u00e3o. Todos os atletas que completarem a prova ter\u00e3o direito a medalhas.\u00a0<\/span><\/p>\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\"><span class=\"x_x_ContentPasted4\">De acordo com o diretor vice-presidente da Agrovale, Denisson Flores, comemorar os 50 anos da empresa promovendo os esportes \u00e9 uma atitude extremamente saud\u00e1vel. &#8220;N\u00f3s temos uma rela\u00e7\u00e3o muito pr\u00f3xima com os movimentos esportivos do Vale. Patrocinamos a Meia Maratona Tiradentes, Corrida Tiradentinhos e a etapa regional do Campeonato Baiano de Ciclismo de Estrada\/ CRI, al\u00e9m de eventos mais recentes a exemplo do Triathlon M\u00e3e Malvada e a Copa Vela Juazeiro de Windsurf. No nosso anivers\u00e1rio n\u00e3o poder\u00edamos comemorar de forma diferente&#8221;, ressaltou.\u00a0<\/span><\/p>\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_x_MsoNormal\" style=\"text-align: justify;\"><span class=\"x_x_ContentPasted4\">As inscri\u00e7\u00f5es poder\u00e3o ser feitas at\u00e9 o dia 8 de setembro atrav\u00e9s do website: www.cronoschip.com.br.Para a categoria Geral ser\u00e1 cobrada uma taxa R$ 22,00, que ser\u00e1 destinada \u00e0 institui\u00e7\u00f5es filantr\u00f3picas de Juazeiro e Petrolina. A inscri\u00e7\u00e3o para a categoria Funcion\u00e1rio ser\u00e1 gratuita. A organiza\u00e7\u00e3o da corrida tamb\u00e9m ir\u00e1 providenciar transporte gratuito com sa\u00edda \u00e0s 6h, da orla de Juazeiro, em frente ao ponto de embarque das barquinhas e retorno a partir das 10h.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o percurso nas depend\u00eancias da pr\u00f3pria empresa, a prova vai come\u00e7ar \u00e0s 7h30, e poder\u00e3o participar atletas de ambos os sexos e idade igual ou superior a 14 anos. Os participantes ir\u00e3o receber um kit de corrida, composto por uma sacola (a definir), camiseta de poliamida,<\/p>\n","protected":false},"author":5,"featured_media":395254,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-395253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/corrida-agrovale.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/395253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=395253"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/395253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/395254"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=395253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=395253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=395253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}