{"id":396294,"date":"2022-08-18T09:54:43","date_gmt":"2022-08-18T12:54:43","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=396294"},"modified":"2022-08-18T09:54:43","modified_gmt":"2022-08-18T12:54:43","slug":"guarda-municipal-intensifica-acoes-de-seguranca-e-fortalece-atuacao-social-em-juazeiro","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/guarda-municipal-intensifica-acoes-de-seguranca-e-fortalece-atuacao-social-em-juazeiro\/","title":{"rendered":"Guarda Municipal intensifica a\u00e7\u00f5es de seguran\u00e7a e fortalece atua\u00e7\u00e3o social em Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p dir=\"ltr\" style=\"text-align: justify;\">A Guarda Civil Municipal (GCM) de Juazeiro tem um papel fundamental dentro da estrutura da seguran\u00e7a p\u00fablica e tamb\u00e9m desenvolve um papel de transforma\u00e7\u00e3o social important\u00edssimo na cidade. Ao longo da atual gest\u00e3o, a GCM vem se fortalecendo e ganhando o reconhecimento da popula\u00e7\u00e3o.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-396295 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1-640x426.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda1.jpg 1048w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">No dia a dia de trabalho, durante rondas pela cidade, as equipes da GCM se deparam com pessoas em situa\u00e7\u00e3o de vulnerabilidade. Al\u00e9m de fazer o encaminhamento a outros \u00f3rg\u00e3os da Prefeitura, como as secretarias de Sa\u00fade e de Desenvolvimento Social, sempre acontece mobiliza\u00e7\u00f5es de agentes para a arrecada\u00e7\u00e3o de alimentos, material de higiene e limpeza e fraldas geri\u00e1tricas, por exemplo. A GCM tamb\u00e9m costuma fazer doa\u00e7\u00f5es para institui\u00e7\u00f5es filantr\u00f3picas da cidade, auxiliando essas institui\u00e7\u00f5es de forma imediata.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-396297 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-620x349.jpeg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-620x349.jpeg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-300x169.jpeg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-768x432.jpeg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-1536x864.jpeg 1536w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-160x90.jpeg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-480x270.jpeg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3-640x360.jpeg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda3.jpeg 1599w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Para o inspetor-chefe da GCM, Gilson Santos, o papel social \u00e9 essencial e vem atrelado ao dever de proteger. \u201cNosso papel sempre ir\u00e1 al\u00e9m do trabalho de agentes da seguran\u00e7a p\u00fablica, pois entendemos que tamb\u00e9m \u00e9 o nosso dever ajudar no que for poss\u00edvel para melhorar a vida dos mais carentes e de toda popula\u00e7\u00e3o. Em outras palavras, nossa atribui\u00e7\u00e3o com a sociedade \u00e9, tamb\u00e9m, promover o bem-estar das pessoas, ultrapassando a garantia da seguran\u00e7a\u201d, destaca Santos.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">O chefe operacional da GCM, Jailson Silva, refor\u00e7a que as iniciativas sociais da corpora\u00e7\u00e3o v\u00e3o prosseguir. \u201cVimos a necessidade de realizar essas a\u00e7\u00f5es sociais para ajudar as pessoas que mais precisam. Com a ajuda dos nossos colegas de trabalho, pudemos contribuir para o bem-estar de muitas fam\u00edlias em diversas comunidades, como na \u00faltima semana, que fizemos doa\u00e7\u00f5es de cestas b\u00e1sicas no Novo Encontro, Sol Levante, Sol Nascente, Malhada da Areia e Alto da Maravilha\u201d, disse.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Proximidade com a comunidade<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">A Guarda Civil Municipal celebrou 20 anos com diversos investimentos da Prefeitura de Juazeiro, podendo ser citadas algumas ao longo da atual gest\u00e3o, como a instala\u00e7\u00e3o do videomonitoramento e reforma da base da GCM; corre\u00e7\u00e3o das gratifica\u00e7\u00f5es dos agentes, igualando todas; cria\u00e7\u00e3o do Grupamento Ostensivo T\u00e1tico em \u00c1rea Rural (Gotar); Patrulha Maria da Penha; recria\u00e7\u00e3o do Projeto Viva Luciana, com a amplia\u00e7\u00e3o do servi\u00e7o; acordo de colabora\u00e7\u00e3o t\u00e9cnica com a Pol\u00edcia Rodovi\u00e1ria Federal (PRF), aquisi\u00e7\u00e3o de viaturas, entre outras tantas conquistas.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">\u201cA nossa Guarda Civil est\u00e1 trabalhando de forma mais pr\u00f3xima da comunidade, com a prote\u00e7\u00e3o da popula\u00e7\u00e3o, iniciativas sociais e trabalho humanizado, sendo reconhecida pela excel\u00eancia na presta\u00e7\u00e3o dos servi\u00e7os. N\u00e3o temos medido esfor\u00e7os para ajudar e afirmo que, enquanto eu estiver prefeita desta cidade, a nossa GCM pode contar sempre comigo\u201d, expressou a prefeita Suzana Ramos.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Al\u00e9m das opera\u00e7\u00f5es de fiscaliza\u00e7\u00e3o de rotina e trabalhos realizados com as demais for\u00e7as de seguran\u00e7a que atuam no munic\u00edpio, a Guarda Municipal tamb\u00e9m est\u00e1 executando a Opera\u00e7\u00e3o Paz das Comunidades, que leva seguran\u00e7a refor\u00e7ada para bairros, conjuntos residenciais e comunidades de Juazeiro sempre aos finais de semana, cujo objetivo \u00e9 garantir a seguran\u00e7a dos moradores.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">A Guarda Civil de Juazeiro est\u00e1 vinculada \u00e0 Companhia de Seguran\u00e7a, Tr\u00e2nsito e Transporte (CSTT). Para o gestor da pasta, Ten\u00f3rio Filho, a corpora\u00e7\u00e3o tem desempenhado seu papel com excel\u00eancia. \u201cA GCM de Juazeiro vem fazendo um trabalho de excel\u00eancia na nossa cidade, nunca se viu a guarda rodando tanto os distritos e a sede como se v\u00ea hoje. A valoriza\u00e7\u00e3o dos GCMs na gest\u00e3o da prefeita Suzana Ramos tamb\u00e9m \u00e9 de excel\u00eancia porque n\u00f3s nos sentamos, conversamos e buscamos sempre chegar a um acordo. Eu s\u00f3 posso agradecer a todos esses profissionais e dizer que n\u00f3s estamos juntos e mais conquistas vir\u00e3o&#8221;, afirmou.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Atendimento<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">O servi\u00e7o de seguran\u00e7a da GCM funciona 24 horas por dia. Os agentes verificam as mais diversas den\u00fancias que s\u00e3o recebidas atrav\u00e9s dos n\u00fameros 153 (Central de Atendimento) e (74) 3611-9880.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia a dia de trabalho, durante rondas pela cidade, as equipes da GCM se deparam com pessoas em situa\u00e7\u00e3o de vulnerabilidade. Al\u00e9m de fazer o encaminhamento a outros \u00f3rg\u00e3os da Prefeitura, como as secretarias de Sa\u00fade e de Desenvolvimento Social, sempre acon<\/p>\n","protected":false},"author":5,"featured_media":396296,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-396294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/guarda2.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/396294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=396294"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/396294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/396296"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=396294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=396294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=396294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}