{"id":396693,"date":"2022-08-24T05:19:19","date_gmt":"2022-08-24T08:19:19","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=396693"},"modified":"2022-08-24T05:19:19","modified_gmt":"2022-08-24T08:19:19","slug":"lula-promete-volta-do-pac-e-do-minha-casa-minha-vida","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/lula-promete-volta-do-pac-e-do-minha-casa-minha-vida\/","title":{"rendered":"Lula promete volta do PAC e do Minha Casa Minha Vida"},"content":{"rendered":"<h1 class=\"titulo_noticia\"><\/h1>\n<div class=\"abas\">\n<div id=\"pills-tabContent\" class=\"tab-content\">\n<div id=\"abanoticia\" class=\"tab-pane fade show active\" role=\"tabpanel\" aria-labelledby=\"pills-noticia-tab\">\n<div id=\"items_noticia\">\n<div class=\"row\">\n<div id=\"autorNoticia\" class=\"w-100 d-block\"><span class=\"d-inline\"><small class=\"text-muted\">Por:<\/small>\u00a0Marcelo Brand\u00e3o\/Ag\u00eancia Brasil<br \/>\n<\/span><small class=\"text-muted\"><\/small><\/div>\n<\/div>\n<\/div>\n<div class=\"news_body\">\n<div class=\"font_change\">\n<div class=\"w-100 d-block float-end mb-3\">\n<div id=\"st-1\" class=\"sharethis-inline-share-buttons st-right  st-inline-share-buttons st-animated\">\n<div class=\"st-btn\" data-network=\"email\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/email.svg\" alt=\"email sharing button\" \/><\/div>\n<div class=\"st-btn\" data-network=\"sms\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/sms.svg\" alt=\"sms sharing button\" \/><\/div>\n<div class=\"st-btn st-last\" data-network=\"sharethis\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/sharethis.svg\" alt=\"sharethis sharing button\" \/><\/div>\n<\/div>\n<\/div>\n<div class=\"fonteNoticia\">\n<table class=\"table-light table-striped image center\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-396694 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate-620x371.jpg\" alt=\"\" width=\"620\" height=\"371\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate-620x371.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate-300x179.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate-768x459.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate-160x96.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate-640x383.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate.jpg 1170w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"zebra\">Foto: Reprodu\u00e7\u00e3o\/Facebook<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>Candidato \u00e0 Presid\u00eancia da Rep\u00fablica pelo PT, Lula se reuniu com empres\u00e1rios da constru\u00e7\u00e3o civil em S\u00e3o Paulo. Ele recebeu um documento com propostas para estimular o crescimento do setor de habita\u00e7\u00e3o e afirmou que retomar\u00e1 dois programas criados na \u00e9poca em que era presidente da Rep\u00fablica, o Minha Casa Minha Vida e o Programa de Acelera\u00e7\u00e3o do Crescimento (PAC).<\/div>\n<div><\/div>\n<div>\u201cO PAC foi uma coisa extraordin\u00e1ria porque n\u00e3o foi um projeto de constru\u00e7\u00e3o de infraestrutura pensado a partir do gabinete para Presid\u00eancia da Rep\u00fablica. Ele foi constru\u00eddo com empres\u00e1rios, governadores e prefeitos. E \u00e9 o que eu pretendo retomar, se a gente ganhar as elei\u00e7\u00f5es, a partir do dia 1\u00ba de janeiro [de 2023]\u201d, disse Lula.<\/div>\n<div class=\"google-auto-placed ap_container\"><ins class=\"adsbygoogle adsbygoogle-noablate\" data-ad-format=\"auto\" data-ad-client=\"ca-pub-9820262637650134\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><\/p>\n<div id=\"aswift_1_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><\/div>\n<p><\/ins><\/div>\n<div><\/div>\n<div>\u00a0Aos empres\u00e1rios, Lula tamb\u00e9m afirmou sua disposi\u00e7\u00e3o em retomar o Minha Casa, Minha Vida, programa habitacional voltado \u00e0s camadas de baixa renda e que foi substitu\u00eddo em 2021 pelo programa Casa Verde Amarela. \u201cA primeira coisa que eu quero dizer para voc\u00eas \u00e9 que o Minha Casa Minha Vida vai voltar a ser um programa de governo\u201d, afirmou o candidato. \u201cO Estado precisa se cercar de possibilidade econ\u00f4mica, de usar seus bancos para ajudar, ou atrav\u00e9s do Or\u00e7amento da Uni\u00e3o, ou atrav\u00e9s de financiamento, a gente garantir que as casas possam ser constru\u00eddas\u201d.<\/div>\n<div><\/div>\n<div><strong>Pacto Federativo<\/strong><\/div>\n<div><\/div>\n<div>Lula pregou a uni\u00e3o de estados, munic\u00edpios e governo federal na administra\u00e7\u00e3o dos problemas do pa\u00eds. Ele afirmou que, caso ven\u00e7a a elei\u00e7\u00e3o, far\u00e1 uma reuni\u00e3o com todos os governadores, independente de partido pol\u00edtico. \u201cA segunda coisa que vamos fazer \u00e9, na primeira semana depois da posse, uma reuni\u00e3o com 27 governadores de estado para que a gente reestabele\u00e7a o pacto federativo nesse pa\u00eds. \u00c9 importante passar para a sociedade a ideia de que governadores e presidente da Rep\u00fablica n\u00e3o ser\u00e3o inimigos\u201d.<\/div>\n<div><\/div>\n<div>O candidato exaltou a companhia de Geraldo Alckmin, seu candidato a vice-presidente. Com o intuito de demonstrar disposi\u00e7\u00e3o em colocar de lado posi\u00e7\u00f5es ideol\u00f3gicas durante seu governo, Lula exaltou o trabalho de Alckmin quando ele integrava o PSDB e governou S\u00e3o Paulo. Lula disse que \u201cadvers\u00e1rios pol\u00edticos n\u00e3o precisam ser inimigos\u201d e defendeu essa uni\u00e3o de todos em torno do desenvolvimento do pa\u00eds. \u201cEssa jun\u00e7\u00e3o nossa \u00e9 a garantia que a gente quer dar que esse pa\u00eds vai deixar de discutir coisa secund\u00e1ria e vai come\u00e7ar a discutir aquilo que interessa \u00e0 sociedade brasileira\u201d.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO PAC foi uma coisa extraordin\u00e1ria porque n\u00e3o foi um projeto de constru\u00e7\u00e3o de infraestrutura pensado a partir do gabinete para Presid\u00eancia da Rep\u00fablica. Ele foi constru\u00eddo com empres\u00e1rios, governadores e prefeitos. E \u00e9 o que eu pretendo retomar, se a gente ganhar as elei\u00e7\u00f5es, a partir do dia 1\u00ba de janeiro [de 2023]\u201d, disse Lula.\u00a0<\/p>\n","protected":false},"author":5,"featured_media":396694,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-396693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-no-debate.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/396693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=396693"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/396693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/396694"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=396693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=396693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=396693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}