{"id":397051,"date":"2022-08-29T08:18:03","date_gmt":"2022-08-29T11:18:03","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=397051"},"modified":"2022-08-29T08:18:03","modified_gmt":"2022-08-29T11:18:03","slug":"neta-e-filha-de-gretchen-trocam-indiretas-apos-polemica-com-adriano","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/neta-e-filha-de-gretchen-trocam-indiretas-apos-polemica-com-adriano\/","title":{"rendered":"Neta e filha de Gretchen trocam indiretas ap\u00f3s pol\u00eamica com Adriano"},"content":{"rendered":"<div class=\"col-sm-12 ig-container_headerText\">\n<h1 id=\"noticia-titulo-h1\" class=\"noticia-titulo-h1-ig_V04\"><\/h1>\n<h2 id=\"noticia-olho\">Jenny e Bia Miranda passaram a se alfinetar nas redes sociais ap\u00f3s a neta de Gretchen assumir ficada com jogador Adriano<\/h2>\n<\/div>\n<div id=\"ad_billboard\" class=\"betOrBillboard\" data-google-query-id=\"CI6erpT26_kCFf4GuQYdpe0PNw\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/gente.ig.com.br\/billboard_0__container__\"><\/div>\n<\/div>\n<div id=\"noticia-other\" class=\"noticia-other-ig_V04\">\n<div class=\"author-container\">\n<p>Por\u00a0<strong>Ag\u00eancia O Globo<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"contentNoticia\">\n<div class=\"main-content\">\n<div class=\"row\">\n<section class=\"noticia col-sm-12 plf-0\">\n<div id=\"noticia\">\n<div class=\"Noticia_Foto\">\n<figure class=\"foto-legenda \">\n<div class=\"foto-legenda-img\">\n<div id=\"standard_1\" class=\"st-placement standard_1 inImage\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\">\n<div class=\"st-adunit-ad st-reset\">\n<div class=\"st-display-render st-reset\">\n<div class=\"st-reset\">\n<div class=\"important-styled st-canvas-container open Square full-display-standard fssquz2\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Neta de Gretchen Bia Miranda vive pol\u00eamica com m\u00e3e Jenny Miranda \" src=\"https:\/\/i0.statig.com.br\/bancodeimagens\/5v\/9j\/zw\/5v9jzwab7gcf4m6fim9o1ytlk.jpg\" alt=\"Neta de Gretchen Bia Miranda vive pol\u00eamica com m\u00e3e Jenny Miranda \" width=\"906\" height=\"509\" \/><\/div><figcaption class=\"foto-legenda-citacao \"><cite>Reprodu\u00e7\u00e3o\/Instagram &#8211; 24.08.2022<\/cite><\/p>\n<div class=\"foto-legenda-citacao-text\" data-gtm-vis-recent-on-screen-214867_1952=\"2759\" data-gtm-vis-first-on-screen-214867_1952=\"2759\" data-gtm-vis-total-visible-time-214867_1952=\"100\" data-gtm-vis-has-fired-214867_1952=\"1\">Neta de Gretchen Bia Miranda vive pol\u00eamica com m\u00e3e Jenny Miranda<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\"\">Desde que passou a trocar acusa\u00e7\u00f5es p\u00fablicas com a filha devido a um affair com o jogador Adriano Imperador, Jenny Miranda viu as crises de ansiedade aumentarem. Entrou em um per\u00edodo dif\u00edcil para a vida, foi buscar aux\u00edlio m\u00e9dico e percebeu que estava tendo uma reca\u00edda na depress\u00e3o. Com a voz mais baixa que a habitual e os olhos marejados, a filha de\u00a0Gretchen\u00a0falou do momento dif\u00edcil para os seguidores.<\/p>\n<div class=\"publicidade advertising-box\">\n<div id=\"ad_mrec_intext\" data-google-query-id=\"CNO8qJT26_kCFf4GuQYdpe0PNw\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/gente.ig.com.br\/mrec_1__container__\"><\/div>\n<\/div>\n<\/div>\n<p>&#8220;Est\u00e1 muito dif\u00edcil tudo isso, essa situa\u00e7\u00e3o armada, esse show todo. Quem me acompanha sabe que sofro depress\u00e3o h\u00e1 anos, tem relatos aqui. Estou sofrendo com tudo de novo. Meu psicol\u00f3gico est\u00e1 abalado, estou a base de rem\u00e9dios. A verdade sempre vem \u00e0 tona, n\u00e3o demora muito tempo e a\u00ed todo mundo vai saber quem est\u00e1 mentindo nessa hist\u00f3ria. Pe\u00e7o que Deus me d\u00ea for\u00e7as at\u00e9 l\u00e1. Estou com crises de ansiedade, fui medicada. Tinha dado uma parada, porque tinha melhorado, mas tive que voltar&#8221;, disse Jenny.<\/p>\n<p class=\" \">Mais cedo, tanto Jenny quanto Bia Miranda, a filha da influencer e neta de Gretchen, publicaram na web mensagens consideradas como indiretas.<\/p>\n<p>&#8220;N\u00e3o permita que pessoas t\u00f3xicas fa\u00e7am parte da sua vida&#8221;, diz o texto compartilhado por Bia horas depois do trecho publicado por Jenny: &#8220;Ore muito! Porque essa tua for\u00e7a incomoda gente frustrada&#8221;.<\/p>\n<p>Como revelou a coluna Retratos da Vida, do Extra, a fam\u00edlia da rainha do rebolado est\u00e1 abalada ap\u00f3s a neta da cantora, Anna Beatryz Miranda, se envolver com Adriano Imperador. Bia admitiu que ficou com o ex-atleta por duas vezes e se surpreendeu ao ver a m\u00e3e dizendo que n\u00e3o sabia de nada. A jovem a acusou de querer fama e sugeriu que a influenciadora fitness teria sido respons\u00e1vel por vazar a hist\u00f3ria.<\/p>\n<p>&#8220;Sabia desde o come\u00e7o e brigou comigo porque quem quis ficar com ele para ter fama e dinheiro era ela&#8221;, disse.<\/p>\n<p>Al\u00e9m do que Jenny teria chamado de &#8220;furada de olho&#8221; por parte da filha, Bia revelou que a m\u00e3e nunca quis que ela sa\u00edsse mais bonita que ela.<\/p>\n<p>&#8220;Quando eu sa\u00eda bonita, ela pedia para eu trocar de roupa para ela chamar mais aten\u00e7\u00e3o do que eu&#8221;, desabafou.<\/p>\n<p>&#8220;N\u00e3o vou ficar me defendendo, justificando, s\u00f3 n\u00e3o v\u00ea quem \u00e9 cego&#8221;, desabafou Jenny na web ao ser chamada pela filha de mentirosa e interesseira.<\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jenny e Bia Miranda passaram a se alfinetar nas redes sociais ap\u00f3s a neta de Gretchen assumir ficada com jogador Adriano<\/p>\n","protected":false},"author":5,"featured_media":397052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-397051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/neta-e-filha-de-gretchen.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=397051"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397052"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=397051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=397051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=397051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}