{"id":397059,"date":"2022-08-29T09:03:26","date_gmt":"2022-08-29T12:03:26","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=397059"},"modified":"2022-08-29T09:03:26","modified_gmt":"2022-08-29T12:03:26","slug":"bolsonaro-chama-lula-de-ex-presidiario-em-direito-de-resposta-2","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/bolsonaro-chama-lula-de-ex-presidiario-em-direito-de-resposta-2\/","title":{"rendered":"Bolsonaro chama Lula de &#8216;ex-presidi\u00e1rio&#8217; em direito de resposta"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"col-sm-12 ig-container_headerText\">\n<h2 id=\"noticia-olho\">Candidato \u00e0 reelei\u00e7\u00e3o ainda criticou falas de Simone Tebet sobre trabalho do Planalto durante a pandemia<\/h2>\n<\/div>\n<div id=\"ad_billboard\" class=\"betOrBillboard\" data-google-query-id=\"CKDEt6aA7PkCFZAyuQYd8-MNxQ\">\n<div id=\"google_ads_iframe_\/21737107378\/IG-PUBLISHER\/ultimosegundo.ig.com.br\/billboard_0__container__\"><\/div>\n<\/div>\n<div id=\"noticia-other\" class=\"noticia-other-ig_V04\">\n<div class=\"author-container\">\n<p>Por\u00a0<strong>iG \u00daltimo Segundo<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"contentNoticia\">\n<div class=\"main-content\">\n<div class=\"row\">\n<section class=\"noticia col-sm-12 plf-0\">\n<div id=\"noticia\">\n<div class=\"Noticia_Foto\">\n<figure class=\"foto-legenda \">\n<div class=\"foto-legenda-img\"><img loading=\"lazy\" decoding=\"async\" title=\"Debate na Band re\u00fane candidatos \u00e0 Presid\u00eancia\" src=\"https:\/\/i0.statig.com.br\/bancodeimagens\/a1\/d0\/me\/a1d0mez6uw6tzd3x9nfyyj61e.jpg\" alt=\"Debate na Band re\u00fane candidatos \u00e0 Presid\u00eancia\" width=\"906\" height=\"509\" \/><\/div><figcaption class=\"foto-legenda-citacao \"><cite>Reprodu\u00e7\u00e3o\/Band<\/cite><\/p>\n<div class=\"foto-legenda-citacao-text\" data-gtm-vis-recent-on-screen-214867_1952=\"2985\" data-gtm-vis-first-on-screen-214867_1952=\"2985\" data-gtm-vis-total-visible-time-214867_1952=\"100\" data-gtm-vis-has-fired-214867_1952=\"1\">Debate na Band re\u00fane candidatos \u00e0 Presid\u00eancia<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\" \">O presidente Jair Bolsonaro (PL) atacou o candidato do PT e ex-presidente Lula ap\u00f3s ser criticado por decretar sigilo de 100 anos em documentos durante a pandemia. Bolsonaro chamou Lula de &#8216;presidi\u00e1rio&#8217;, relembrando o tempo em que o petista foi acusado por corrup\u00e7\u00e3o pela Lava Jato.<\/p>\n<p>Bolsonaro deu a declara\u00e7\u00e3o durante o direito de resposta que teve ap\u00f3s ser chamado de &#8216;mau-car\u00e1ter&#8217; pelo candidato Ciro Gomes (PDT). O presidente ainda relembrou uma fala do ex-presidente sobre a Covid-19.<\/p>\n<p>&#8220;Lula, &#8216;ainda bem que a natureza criou esse mo\u00e7o do coronav\u00edrus&#8217;,que moral tem para falr de Deus, hein, ex-presidi\u00e1rio, nenhuma moral. Sigilo de cem anos para as quest\u00f5es pessoais, meu cart\u00e3o de vacina ou quem me visita, nada mais disso&#8221;, disse Bolsonaro, em debate da Band neste domingo (28).<\/p>\n<p>O candidato do PL ainda criticou as falas de Simone Tebet (MDB) sobre o Or\u00e7amento Secreto. Bolsonaro disse que vetou as emendas de relator, mas que foi voto vencido no Congresso Nacional. Tebet havia dito que a distribui\u00e7\u00e3o de valores carimbadas poderia ser o maior caso de corrup\u00e7\u00e3o do pa\u00eds.<\/p>\n<p>O presidente ainda rebateu as afirma\u00e7\u00f5es da emedebista sobre as acusa\u00e7\u00f5es de corrup\u00e7\u00e3o do Planalto durante a pandemia de Covid-19.<\/p>\n<p>&#8220;E dizer a voc\u00eas tamb\u00e9m, a vacina, est\u00e1 de brincadeira a nobre senadora? Tentou corromper, cad\u00ea a corrup\u00e7\u00e3o? Cad\u00ea o contrato assinado? Cad\u00ea a nota? N\u00e3o tem nada! Mentiram ao meu respeito&#8221;.<\/p>\n<p>Esse \u00e9 o primeiro encontro entre os candidatos \u00e0 presid\u00eancia da Rep\u00fablica nas Elei\u00e7\u00f5es deste ano. Lula e Bolsonaro lideram as pesquisas de opini\u00e3o, seguidos por Ciro Gomes e Simone Tebet (MDB). Felipe D&#8217;Avila (Novo) e Sorarya Thronicke (Uni\u00e3o Brasil) tamb\u00e9m participam do debate.<\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Candidato \u00e0 reelei\u00e7\u00e3o ainda criticou falas de Simone Tebet sobre trabalho do Planalto durante a pandemia<\/p>\n","protected":false},"author":5,"featured_media":397060,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-397059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/lula-e-ciro-boa.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=397059"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397060"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=397059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=397059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=397059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}