{"id":397166,"date":"2022-08-30T06:40:08","date_gmt":"2022-08-30T09:40:08","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=397166"},"modified":"2022-08-30T06:40:08","modified_gmt":"2022-08-30T09:40:08","slug":"fiocruz-registra-imagens-de-replicacao-do-virus-variola-dos-macacos-em-celula","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/fiocruz-registra-imagens-de-replicacao-do-virus-variola-dos-macacos-em-celula\/","title":{"rendered":"Fiocruz registra imagens de replica\u00e7\u00e3o do v\u00edrus var\u00edola dos macacos em c\u00e9lula"},"content":{"rendered":"<header class=\"grid_12 prefix_2\">\n<div class=\"tituloNoticia\">\n<h1 class=\"tituloNoticiaDet\"><\/h1>\n<h2 class=\"subTituloDet\">Pesquisa foi feita pelo Laborat\u00f3rio de Morfologia e Morfog\u00eanese Viral<\/h2>\n<\/div>\n<div class=\"descricaoNoticia\">\n<aside class=\"dataAutor\">Por<strong>\u00a0Ag\u00eancia Brasil<\/strong><small><\/small><\/aside>\n<\/div>\n<div class=\"spacer40 mobileNao\"><\/div>\n<\/header>\n<div class=\"imgPadrao grid_12 prefix_2\"><a id=\"imgPrincipalNoticia\" title=\"V\u00edrus da var\u00edola dos macacos  - Foto: Foto: Centro de Controle de Doen\u00e7as\/Divulga\u00e7\u00e3o\" href=\"https:\/\/cdn.folhape.com.br\/img\/pc\/450\/450\/dn_arquivo\/2022\/05\/whatsapp-image-2022-05-07-at-190102.jpeg\" rel=\"gallery\"><picture><source srcset=\"https:\/\/cdn.folhape.com.br\/img\/pc\/450\/450\/dn_arquivo\/2022\/05\/whatsapp-image-2022-05-07-at-190102.jpeg\" media=\"(max-width: 940px)\" \/><source srcset=\"https:\/\/cdn.folhape.com.br\/img\/pc\/1100\/1\/dn_arquivo\/2022\/05\/whatsapp-image-2022-05-07-at-190102.jpeg\" \/><img decoding=\"async\" src=\"https:\/\/cdn.folhape.com.br\/img\/pc\/1100\/1\/dn_arquivo\/2022\/05\/whatsapp-image-2022-05-07-at-190102.jpeg\" alt=\"V\u00edrus da var\u00edola dos macacos\" \/><\/picture><\/a><\/div>\n<div class=\"imgPadrao grid_12 prefix_2\"><small class=\"legendaFoto\">V\u00edrus da var\u00edola dos macacos\u00a0&#8211;\u00a0<em>Foto: Centro de Controle de Doen\u00e7as\/Divulga\u00e7\u00e3o<\/em><\/small><\/div>\n<div class=\"clear\"><\/div>\n<div class=\"spacer40 mobileNao\"><\/div>\n<article class=\"grid_8 prefix_2 textoArea\">Pesquisadores da<strong>\u00a0Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz)<\/strong>\u00a0conseguiram registrar em imagens o momento em que uma c\u00e9lula sofre processo de degenera\u00e7\u00e3o ap\u00f3s infec\u00e7\u00e3o pelo v\u00edrus monkeypox, respons\u00e1vel pela\u00a0<strong>var\u00edola dos macacos<\/strong>.\u00a0A amplia\u00e7\u00e3o da imagem em at\u00e9 40 mil vezes permitiu mostrar de perto as part\u00edculas virais em processo de replica\u00e7\u00e3o no citoplasma da c\u00e9lula.\u00a0<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1479550&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1479550&amp;o=node\" \/><\/p>\n<p>Segundo os pesquisadores, estima-se que o<strong>\u00a0v\u00edrus monkeypox<\/strong>\u00a0me\u00e7a 300 nan\u00f4metros, o que equivale a 0,00003 cent\u00edmetro. Apesar de ser 300 vezes menor que a c\u00e9lula, os cientistas avaliam que ele se replica com facilidade ao conseguir infect\u00e1-la.<\/p>\n<p>A capta\u00e7\u00e3o das imagens se deu durante um estudo sobre replica\u00e7\u00e3o viral, a partir de uma amostra cl\u00ednica de um paciente infectado que foi posta em contato com c\u00e9lulas de linhagem Vero, frequentemente utilizadas para ensaios in vitro e isolamento viral.<\/p>\n<p>A pesquisa \u00e9 coordenada pela chefe do Laborat\u00f3rio de Morfologia e Morfog\u00eanese Viral, Debora Ferreira Barreto Vieira, com colabora\u00e7\u00e3o de sua equipe (Milene Dias Miranda, Gabriela Cardoso Caldas e Vivian Ferreira), em parceria com pesquisadores do Laborat\u00f3rio de Enterov\u00edrus, refer\u00eancia em diagn\u00f3stico laboratorial em monkeypox para o Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>A\u00a0<strong>monkeypox<\/strong>, tamb\u00e9m chamada de var\u00edola dos macacos, foi declarada Emerg\u00eancia Internacional de Sa\u00fade P\u00fablica pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade e j\u00e1 causou mais de 40 mil casos desde que o v\u00edrus saiu das regi\u00f5es do continente africano onde costumava ser end\u00eamico.<\/p>\n<p>A doen\u00e7a pode ser transmitida por contato pessoal e \u00edntimo, como beijo, abra\u00e7o e rela\u00e7\u00f5es sexuais, por contato com feridas, crostas ou fluidos corporais, e tamb\u00e9m\u00a0por secre\u00e7\u00f5es respirat\u00f3rias durante contato pessoal prolongado.<\/p>\n<p>Os sintomas podem incluir les\u00f5es na pele, febre, dor no corpo e dor de cabe\u00e7a, entre outros. Pessoas com esses sintomas devem procurar os servi\u00e7os de sa\u00fade para terem acesso \u00e0 testagem.<\/p>\n<p>&nbsp;<\/p>\n<section class=\"bannerBillboardDetalhe\">\n<div id=\"middle\"><\/div>\n<\/section>\n<div class=\"clear\"><\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0monkeypox, tamb\u00e9m chamada de var\u00edola dos macacos, foi declarada Emerg\u00eancia Internacional de Sa\u00fade P\u00fablica pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade e j\u00e1 causou mais de 40 mil casos desde que o v\u00edrus saiu das regi\u00f5es do continente africano onde costumava ser end\u00eamico.<\/p>\n<p>A doen\u00e7a pode ser transmitida por contato<\/p>\n","protected":false},"author":5,"featured_media":397167,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-397166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/virus-da-variola.jpeg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=397166"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397167"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=397166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=397166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=397166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}