{"id":397200,"date":"2022-08-30T07:49:43","date_gmt":"2022-08-30T10:49:43","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=397200"},"modified":"2022-08-30T07:49:43","modified_gmt":"2022-08-30T10:49:43","slug":"fumo-de-terceira-mao-como-substancias-do-cigarro-se-agarram-a-objetos-e-fazem-mal-a-saude","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/fumo-de-terceira-mao-como-substancias-do-cigarro-se-agarram-a-objetos-e-fazem-mal-a-saude\/","title":{"rendered":"Fumo de terceira m\u00e3o: como subst\u00e2ncias do cigarro &#8216;se agarram&#8217; a objetos e fazem mal \u00e0 sa\u00fade"},"content":{"rendered":"<div class=\"bbc-1151pbn ebmt73l0\" dir=\"ltr\">\n<h1 id=\"content\" class=\"bbc-14gqcmb e1p3vdyi0\" tabindex=\"-1\"><\/h1>\n<\/div>\n<div class=\"e1j2237y6 bbc-q4ibpr ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-1atl7vu euvj3t14\">\n<p>Andr\u00e9 Biernath &#8211; @andre_biernath<\/p>\n<\/div>\n<\/div>\n<div class=\"e1j2237y7 bbc-q4ibpr ebmt73l0\" dir=\"ltr\"><\/div>\n<div class=\"bbc-1ka88fa ebmt73l0\" dir=\"ltr\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-189y18v ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-997y1y eihqrxw0\" data-e2e=\"image-placeholder\"><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg.webp 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg.webp 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg.webp 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg.webp 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\" \/><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\" \/><img loading=\"lazy\" decoding=\"async\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\" src=\"https:\/\/ichef.bbci.co.uk\/news\/640\/cpsprodpb\/B9A9\/production\/_126492574_gettyimages-90201400.jpg\" alt=\"Cigarro e cinzeiro em cima de um sof\u00e1\" width=\"976\" height=\"549\" \/><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div><figcaption class=\"bbc-rhuvwm e6i104o0\" dir=\"ltr\">Malef\u00edcios do fumo de terceira m\u00e3o ainda n\u00e3o s\u00e3o completamente conhecidos<\/p>\n<\/figcaption><div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-3edg7g ebmt73l0\" dir=\"ltr\"><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\"><b>Voc\u00ea j\u00e1 ouviu falar de fumo de terceira m\u00e3o? O conceito \u00e9 direto e simples: as subst\u00e2ncias liberadas durante a queima do cigarro impregnam m\u00f3veis, tecidos ou paredes.<\/b><\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;E elas podem permanecer nesses objetos e superf\u00edcies por dias, semanas, meses ou at\u00e9 anos e representam riscos \u00e0 sa\u00fade&#8221;, completa o oncologista cl\u00ednico Marcelo Cruz, do Hospital S\u00edrio-Liban\u00eas, em S\u00e3o Paulo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Embora esse problema seja descrito em trabalhos cient\u00edficos desde a d\u00e9cada de 1950, ele \u00e9 pouco conhecido em compara\u00e7\u00e3o com o fumo passivo \u2014 quando um indiv\u00edduo que n\u00e3o \u00e9 usu\u00e1rio do tabaco inala diretamente a fuma\u00e7a baforada por algu\u00e9m que esteja pr\u00f3ximo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\"><a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/19117850\/\" aria-label=\"Um levantamento feito em 2009, externo\">Um levantamento feito em 2009<\/a>\u00a0nos Estados Unidos calculou que apenas 43% dos tabagistas acreditam que o fumo de terceira m\u00e3o seria danoso \u00e0s crian\u00e7as, enquanto que 84% deles dizem conhecer bem os perigos do fumo passivo.<\/p>\n<\/div>\n<section class=\"e1j2237y8 bbc-sswtix e8sa160\" role=\"region\" aria-label=\"Publicidade 2\" aria-hidden=\"true\" data-e2e=\"advertisement\"><\/section>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Os especialistas alertam que o contato com esses compostos qu\u00edmicos pode fazer mal \u00e0 sa\u00fade \u2014 e j\u00e1 existem alguns trabalhos preliminares, feitos em roedores, que apontam o risco de problemas comportamentais, como a hiperatividade, e at\u00e9 de les\u00f5es em \u00f3rg\u00e3os como os pulm\u00f5es e o f\u00edgado.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Entenda a seguir o que j\u00e1 se sabe sobre esse fen\u00f4meno e o que pode ser feito para evit\u00e1-lo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<h2 id=\"Mol\u00e9culas-impregnadas\" class=\"bbc-1f03ibc eglt09e0\" tabindex=\"-1\">Mol\u00e9culas impregnadas<\/h2>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Segundo o\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/bvsms.saude.gov.br\/tabagismo-13\/\" aria-label=\"De acordo com o Minist\u00e9rio da Sa\u00fade, externo\">De acordo com o Minist\u00e9rio da Sa\u00fade<\/a>, o cigarro carrega mais de 4,7 mil subst\u00e2ncias t\u00f3xicas.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Algumas delas, como a nicotina, a naftalina e os formalde\u00eddos, s\u00e3o liberadas durante o processo de queima e ficam vagando pelo ambiente misturadas \u00e0 fuma\u00e7a.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Aos poucos, elas &#8220;grudam&#8221; nas superf\u00edcies e nos objetos, principalmente naqueles que s\u00e3o revestidos por tecidos, como tapetes, carpetes, toalhas, cortinas e na pr\u00f3pria roupa.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Muitos desses compostos tamb\u00e9m j\u00e1 foram detectados &#8220;agarrados&#8221; aos m\u00f3veis e \u00e0 tinta das paredes.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">O primeiro trabalho sobre o tema\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5716630\/\" aria-label=\"foi publicado em 1953, externo\">foi publicado em 1953<\/a>\u00a0por m\u00e9dicos americanos. Eles demonstraram que a nicotina se condensa (passa do estado gasoso para o l\u00edquido) e, quando aplicada nas costas de ratos, causaria tumores de pele.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Em 1991,\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/2006900\/\" aria-label=\"uma investiga\u00e7\u00e3o feita, externo\">uma investiga\u00e7\u00e3o feita<\/a>\u00a0na Dinamarca encontrou part\u00edculas dessa mesma subst\u00e2ncia (que causa uma depend\u00eancia qu\u00edmica muito forte) na poeira de casas onde moravam fumantes.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">J\u00e1 em 2008, um grupo da Universidade Estadual de San Diego, nos EUA,\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/19023838\/\" aria-label=\"avaliou subst\u00e2ncias encontradas nos carros de tabagistas, externo\">avaliou subst\u00e2ncias encontradas nos carros de tabagistas<\/a>\u00a0e descobriu que at\u00e9 o painel do ve\u00edculo carrega poluentes encontrados nesse produto, mesmo que a pessoa n\u00e3o tenha o costume de acender o cigarro quando est\u00e1 dirigindo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Mais recentemente, em mar\u00e7o de 2020,\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/news.yale.edu\/2020\/03\/04\/third-hand-smoke-no-joke-can-convey-hazardous-chemicals\" aria-label=\"uma equipe da Universidade Yale, externo\">uma equipe da Universidade Yale<\/a>, tamb\u00e9m nos Estados Unidos, mediu a presen\u00e7a de alguns desses compostos qu\u00edmicos numa sala de cinema.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Os cientistas descobriram que em filmes com uma classifica\u00e7\u00e3o et\u00e1ria mais restrita (o que indica a presen\u00e7a de um n\u00famero maior de adultos e possivelmente mais fumantes naquele espa\u00e7o fechado) h\u00e1 uma concentra\u00e7\u00e3o consider\u00e1vel de compostos danosos \u00e0 sa\u00fade, mesmo que seja proibido fumar neste local.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Os autores ent\u00e3o conclu\u00edram que os fumantes carregam consigo esses qu\u00edmicos por meio da pele e das roupas, mesmo que n\u00e3o estejam tragando um cigarro naquele exato momento. Eles estimaram que a quantidade de compostos &#8220;agarrados&#8221; ao corpo dessas pessoas chega a equivaler ao contato de um a dez cigarros pelo fumo passivo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Por fim, Cruz cita\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/jamanetwork.com\/journals\/jamanetworkopen\/fullarticle\/2788753\" aria-label=\"um trabalho publicado em fevereiro deste ano, externo\">um trabalho publicado em fevereiro deste ano<\/a>, em que os cientistas analisaram a presen\u00e7a de nicotina nas m\u00e3os de crian\u00e7as.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">De 311 volunt\u00e1rios com menos de 12 anos que n\u00e3o tinham contato direto com algum fumante, 296 (ou 95% do total) apresentavam essa subst\u00e2ncia na superf\u00edcie da pele.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">J\u00e1 num grupo de 193 crian\u00e7as cujos familiares s\u00e3o usu\u00e1rios do tabaco, essa taxa chegou a 97,9%.<\/p>\n<\/div>\n<div class=\"bbc-sffzb7 e1hrqbfn0\">\n<div class=\"bbc-1ka88fa ebmt73l0\" dir=\"ltr\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-189y18v ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-997y1y eihqrxw0\" data-e2e=\"image-placeholder\">\n<div class=\"lazyload-wrapper \"><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg.webp 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg.webp 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg.webp 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg.webp 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\" \/><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\" \/><img loading=\"lazy\" decoding=\"async\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\" src=\"https:\/\/ichef.bbci.co.uk\/news\/640\/cpsprodpb\/12ED9\/production\/_126492577_gettyimages-1331977499.jpg\" alt=\"Pessoa segura cigarro com a m\u00e3o com uma crian\u00e7a ao fundo\" width=\"976\" height=\"549\" \/><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><figcaption class=\"bbc-rhuvwm e6i104o0\" dir=\"ltr\">Crian\u00e7as s\u00e3o mais vulner\u00e1veis ao fumo de terceira m\u00e3o<\/p>\n<\/figcaption><div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-3edg7g ebmt73l0\" dir=\"ltr\"><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<h2 id=\"Riscos-pouco-conhecidos\" class=\"bbc-1f03ibc eglt09e0\" tabindex=\"-1\">Riscos pouco conhecidos<\/h2>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Embora os especialistas se preocupem com essa exposi\u00e7\u00e3o a tantos compostos qu\u00edmicos, s\u00e3o poucas as pesquisas que estimam com exatid\u00e3o os impactos do fumo de terceira m\u00e3o na sa\u00fade.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\"><a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3906039\/#:~:text=In%20lung%2C%20THS%20stimulates%20excess,obstructive%20pulmonary%20disease%20and%20asthma\" aria-label=\"Um estudo feito na Universidade da Calif\u00f3rnia em Riverside, externo\">Um estudo feito na Universidade da Calif\u00f3rnia em Riverside<\/a>, nos EUA, avaliou em roedores os poss\u00edveis estragos do contato de terceira m\u00e3o com as subst\u00e2ncias do cigarro.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Depois de um tempo, os animais expostos a objetos contaminados por esses compostos qu\u00edmicos foram diagnosticados com alguns problemas f\u00edsicos e comportamentais.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">As cobaias sofreram com danos nos pulm\u00f5es e tinham mais propens\u00e3o a condi\u00e7\u00f5es inflamat\u00f3rias, como a Doen\u00e7a Pulmonar Obstrutiva Cr\u00f4nica (DPOC) e a asma. Eles tamb\u00e9m apresentaram altera\u00e7\u00f5es no f\u00edgado que precedem quadros como cirrose, c\u00e2ncer e doen\u00e7as cardiovasculares.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Os cientistas tamb\u00e9m realizaram testes comportamentais e viram que os ratos expostos ao fumo de terceira m\u00e3o demonstravam com mais frequ\u00eancia sinais de hiperatividade.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Que fique claro: pesquisas desse tipo s\u00e3o consideradas preliminares e n\u00e3o \u00e9 poss\u00edvel afirmar com toda a certeza que esses mesmos problemas se repetem nas pessoas. Mesmo assim, elas servem de base para que outros estudos, com volunt\u00e1rios humanos, possam acontecer no futuro.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;Infelizmente, ainda s\u00e3o poucos os dados que temos sobre o fumo de terceira m\u00e3o ou do quanto risco ele representa para o desenvolvimento de um c\u00e2ncer&#8221;, admite Cruz.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;Mesmo assim, esse problema deve ser encarado com preocupa\u00e7\u00e3o, ainda mais quando consideramos as crian\u00e7as, que t\u00eam contato com muitas superf\u00edcies contaminadas&#8221;, complementa o oncologista.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">A pr\u00f3pria estatura do p\u00fablico infantil j\u00e1 facilita essa proximidade com tapetes e m\u00f3veis onde esses compostos do cigarro se depositam.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Al\u00e9m disso, os pequenos correm maior risco por levarem a m\u00e3o \u00e0 boca com mais frequ\u00eancia e estarem num est\u00e1gio de forma\u00e7\u00e3o dos \u00f3rg\u00e3os vitais e do pr\u00f3prio sistema imunol\u00f3gico.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<h2 id=\"O-que-fazer\" class=\"bbc-1f03ibc eglt09e0\" tabindex=\"-1\">O que fazer?<\/h2>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Os especialistas apontam que a recomenda\u00e7\u00e3o mais \u00f3bvia para diminuir o risco do fumo direto, passivo ou de terceira m\u00e3o \u00e9 simplesmente n\u00e3o fumar.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Existem tratamentos que ajudam a largar o v\u00edcio \u2014 alguns deles est\u00e3o dispon\u00edveis, inclusive, no Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\"><a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/tobacco\" aria-label=\"A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) calcula, externo\">A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) calcula<\/a>\u00a0que o cigarro causa mais de 8 milh\u00f5es de mortes todos os anos.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">O contato direto ou indireto com todas as milhares de subst\u00e2ncias contribui para o desenvolvimento de mais de 15 tipos de c\u00e2ncer diferentes, al\u00e9m de estar relacionado com infarto, acidente vascular cerebral (AVC), DPOC, tuberculose, infec\u00e7\u00f5es respirat\u00f3rias, \u00falceras no est\u00f4mago e no intestino, impot\u00eancia sexual, infertilidade e catarata.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\"><a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/www.gov.br\/inca\/pt-br\/assuntos\/causas-e-prevencao-do-cancer\/tabagismo#:~:text=No%20Brasil%2C%20443%20pessoas%20morrem,mortes%20anuais%20poderiam%20ser%20evitadas\" aria-label=\"O Instituto Nacional de C\u00e2ncer (Inca) estima, externo\">O Instituto Nacional de C\u00e2ncer (Inca) estima<\/a>\u00a0que 443 brasileiros morram todos os dias por causa do tabagismo. Por ano, 161 mil mortes relacionadas ao cigarro poderiam ser evitadas no pa\u00eds.<\/p>\n<\/div>\n<div class=\"bbc-1ka88fa ebmt73l0\" dir=\"ltr\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-189y18v ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-997y1y eihqrxw0\" data-e2e=\"image-placeholder\">\n<div class=\"lazyload-wrapper \"><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg.webp 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg.webp 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg.webp 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg.webp 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\" \/><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\" \/><img loading=\"lazy\" decoding=\"async\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\" src=\"https:\/\/ichef.bbci.co.uk\/news\/640\/cpsprodpb\/C600\/production\/_125988605_gettyimages-1337775743.jpg\" alt=\"Pessoa tira cigarro de ma\u00e7o\" width=\"976\" height=\"549\" \/><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><figcaption class=\"bbc-rhuvwm e6i104o0\" dir=\"ltr\">Um total de 443 brasileiros morrem todos os dias por causa do tabagismo<\/p>\n<\/figcaption><div class=\"bbc-172p16q ebmt73l0\" dir=\"ltr\">\n<div class=\"bbc-3edg7g ebmt73l0\" dir=\"ltr\"><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">J\u00e1 para aqueles que n\u00e3o desejam abandonar o cigarro agora, a dica \u00e9 nunca fumar em ambientes fechados ou pr\u00f3ximos demais da casa, do escrit\u00f3rio ou de espa\u00e7os p\u00fablicos.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">A remo\u00e7\u00e3o de muitos desses compostos qu\u00edmicos que est\u00e3o &#8220;agarrados&#8221; em objetos e superf\u00edcies parece algo dif\u00edcil de fazer.\u00a0<a class=\"bbc-n8oauk e1p3sufg0\" href=\"https:\/\/www.cancercenter.com\/community\/blog\/2019\/01\/thirdhand-smoke-what-is-it-and-what-are-its-risks\" aria-label=\"Uma publica\u00e7\u00e3o, externo\">Uma publica\u00e7\u00e3o<\/a>\u00a0dos Centros de Tratamento do C\u00e2ncer da Am\u00e9rica, nos EUA, aponta que &#8220;os m\u00e9todos de limpeza normais n\u00e3o s\u00e3o efetivos contra esses poluentes&#8221;.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;Na maioria das vezes, a \u00fanica op\u00e7\u00e3o \u00e9 trocar carpetes e pintar de novo as paredes da casa&#8221;, informa o texto.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">Para Cruz, o conceito do fumo de terceira m\u00e3o &#8220;refor\u00e7a como \u00e9 importante manter o ambiente limpo e livre do cigarro&#8221;.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;Como se sabe, algumas dessas subst\u00e2ncias podem ficar impregnadas por semanas, meses ou at\u00e9 anos e eventualmente prejudicar a sa\u00fade de pessoas que nem estavam ali junto com os fumantes.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;Estamos t\u00e3o habituados a falar dos riscos do tabagismo ou do fumo passivo que \u00e0s vezes esquecemos desses efeitos indiretos. Ou seja, n\u00e3o basta apenas fumar num outro c\u00f4modo da casa ou abrir uma janela para dissipar a fuma\u00e7a&#8221;, continua o oncologista.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr ebmt73l0\" dir=\"ltr\">\n<p class=\"bbc-hhl7in e17g058b0\" dir=\"ltr\">&#8220;\u00c9 preciso pensar nas crian\u00e7as e em como um h\u00e1bito pode fazer mal a toda uma popula\u00e7\u00e3o que \u00e9 mais vulner\u00e1vel&#8221;, conclui.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Algumas delas, como a nicotina, a naftalina e os formalde\u00eddos, s\u00e3o liberadas durante o processo de queima e ficam vagando pelo ambiente misturadas \u00e0 fuma\u00e7a.<\/p>\n","protected":false},"author":5,"featured_media":397201,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-397200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/cigarro-no-cinzeiro.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=397200"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397201"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=397200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=397200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=397200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}