{"id":397368,"date":"2022-09-02T05:13:35","date_gmt":"2022-09-02T08:13:35","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=397368"},"modified":"2022-09-02T05:13:35","modified_gmt":"2022-09-02T08:13:35","slug":"prefeitura-de-sento-se-alinha-os-ultimos-preparativos-para-o-desfile-civico-2022","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/prefeitura-de-sento-se-alinha-os-ultimos-preparativos-para-o-desfile-civico-2022\/","title":{"rendered":"Prefeitura de Sento-S\u00e9 alinha os \u00faltimos preparativos para o Desfile C\u00edvico 2022"},"content":{"rendered":"<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\" align=\"center\"><b>\u00a0<\/b><\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">Com o tema: \u2018Sento-S\u00e9 eu construo a sua hist\u00f3ria\u2019 a Prefeitura de Sento-S\u00e9, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (SME) e da Ger\u00eancia Municipal de Cultura vai realizar nos dias 06 e 07 de setembro grandes e memor\u00e1veis desfiles c\u00edvicos em celebra\u00e7\u00e3o ao dia da Independ\u00eancia do Brasil, 7 de setembro. Nesta semana representantes de diferentes pasta da gest\u00e3o municipal e representantes da Policia Militar da Bahia e Guarda Civil Municipal estiveram reunidos na sede da Secretaria Municipal de Cultura, para ajustar os \u00faltimos detalhes da organiza\u00e7\u00e3o dos eventos.<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-397370 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/7-de-setembro-em-sento-se-620x419.jpg\" alt=\"\" width=\"620\" height=\"419\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/7-de-setembro-em-sento-se-620x419.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/7-de-setembro-em-sento-se-300x203.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/7-de-setembro-em-sento-se-160x108.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/7-de-setembro-em-sento-se-640x432.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/7-de-setembro-em-sento-se.jpg 745w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">Na ocasi\u00e3o, foi apresentado o cronograma dos desfiles, bem como o mapa do percurso por onde os desfiles v\u00e3o passar e organizada a log\u00edstica para interdi\u00e7\u00e3o das vias. No dia 06 de setembro ser\u00e1 realizada a apresenta\u00e7\u00e3o dos alunos da educa\u00e7\u00e3o infantil e fundamental I, j\u00e1 no dia 07 de setembro o desfile ser\u00e1 dos alunos do Ensino Fundamental, do ensino m\u00e9dio e da Guarda Civil Municipal. V\u00e3o participar do Desfile alunos das redes p\u00fablica municipal e estadual e tamb\u00e9m da rede particular.<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">\u201cNos dois dias os desfiles iniciar\u00e3o \u00e0s 8h. No dia 7 de Setembro al\u00e9m do desfile teremos o tradicional hasteamento das bandeiras, com a presen\u00e7a das autoridades no munic\u00edpio. Teremos 13 escolas participando do desfile totalizando mais de 5 mil alunos\u201d, explica o Secret\u00e1rio Municipal de Educa\u00e7\u00e3o, Jeorge Ribeiro, acrescentando que a escolha do tema para este ano da \u00eanfase aos 190 anos de hist\u00f3ria do munic\u00edpio. \u201cO momento \u00e9 mais que oportuno para manifestar atrav\u00e9s do esp\u00edrito c\u00edvico o amor a nossa cidade, com apresenta\u00e7\u00f5es que v\u00e3o exaltar as tradi\u00e7\u00f5es, cultura, belezas e riquezas naturais, nosso povo e origem\u201d, afirma o secret\u00e1rio.<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Na ocasi\u00e3o, foi apresentado o cronograma dos desfiles, bem como o mapa do percurso por onde os desfiles v\u00e3o passar e organizada a log\u00edstica para interdi\u00e7\u00e3o das vias. No dia 06 de setembro ser\u00e1 realizada a apresenta\u00e7\u00e3o dos alunos da educa\u00e7\u00e3o infantil e fundamental I, j\u00e1 no dia 07 de setembro o desfile ser\u00e1 dos alunos do Ensino Fundamental, do ensino<\/p>\n","protected":false},"author":5,"featured_media":397369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-397368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/desfile-em-sento-se.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=397368"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397369"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=397368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=397368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=397368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}