{"id":397487,"date":"2022-09-02T15:56:28","date_gmt":"2022-09-02T18:56:28","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=397487"},"modified":"2022-09-02T15:56:28","modified_gmt":"2022-09-02T18:56:28","slug":"em-visita-a-horta-do-joao-paulo-ii-em-juazeiro-ellen-carvalho-pt-ressalta-seu-compromisso-com-a-agricultura-familiar","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/em-visita-a-horta-do-joao-paulo-ii-em-juazeiro-ellen-carvalho-pt-ressalta-seu-compromisso-com-a-agricultura-familiar\/","title":{"rendered":"Em visita a horta do Jo\u00e3o Paulo II, em Juazeiro, Ellen Carvalho (PT) ressalta seu compromisso com a agricultura familiar"},"content":{"rendered":"<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">Na manh\u00e3 desta quinta-feira (1) a candidata a deputada estadual Ellen Carvalho (PT) visitou a horta org\u00e2nica comunit\u00e1ria do bairro Jo\u00e3o Paulo II, em Juazeiro, criada h\u00e1 mais de 30 anos, e que atualmente conta com 108 associados, sendo 80 mulheres. S\u00e3o 70 fam\u00edlias envolvidas com a produ\u00e7\u00e3o de diversas culturas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-397488 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro-401x500.jpeg\" alt=\"\" width=\"401\" height=\"500\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro-401x500.jpeg 401w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro-240x300.jpeg 240w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro-768x958.jpeg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro-160x200.jpeg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro-640x798.jpeg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro.jpeg 828w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Ellen conheceu de perto a produ\u00e7\u00e3o de legumes e hortali\u00e7as produzidos na horta, p\u00f4de conversar com as agricultoras e ouvir suas conquistas e dificuldades.\u00a0<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Dona Maria Joaquina Nascimento, aposentada e uma das associadas da horta, contou sua lida no campo e recebeu a candidata com muita carinho: &#8220;Ela \u00e9 uma pessoa \u00f3tima. E eu pe\u00e7o voto para ela&#8221;, disse Dona Joaquina.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Ellen ouviu as reivindica\u00e7\u00f5es dos associados, que pedem mais apoio para que possam produzir mais.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>&#8220;Hoje n\u00f3s precisamos da ajuda de Ellen aqui na nossa horta para nos tirar do fundo do po\u00e7o. A gente paga muito caro em energia e \u00e1gua e isso dificulta o nosso trabalho&#8221;, pediu Davi Costa, agricultor.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Dona Jovita Pereira fez quest\u00e3o de ressaltar o trabalho de Isaac Carvalho, quando \u00e0 frente da Prefeitura de Juazeiro e manifestou sua confian\u00e7a na candidata do ex-gestor.\u00a0<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>&#8220;O que eu espero, o que n\u00f3s esperamos aqui, \u00e9 que ela venha com um bom trabalho, assim como quando Isaac entrou na prefeitura. A gente espera que ela tamb\u00e9m seja uma boa deputada. N\u00f3s esperamos e confiamos nisso,&#8221; declarou a agricultora Jovita Pereira.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>A horta do Jo\u00e3o Paulo II \u00e9 uma prova da import\u00e2ncia social, econ\u00f4mica e ambiental da agricultura familiar. A produ\u00e7\u00e3o dos alimentos org\u00e2nicos da propriedade \u00e9 destinada \u00e0 subsist\u00eancia das fam\u00edlias e tamb\u00e9m vai para o mercado, garantindo renda aos associados. \u00a0<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>&#8220;Foi um momento muito enriquecedor. Trocamos experi\u00eancias sobre a import\u00e2ncia da nossa for\u00e7a. N\u00f3s, mulheres do campo e da cidade, no lar, no trabalho. Ainda, do papel da mulher na agricultura familiar. As mulheres agricultoras da horta do bairro Jo\u00e3o Paulo II, e tamb\u00e9m os agricultores, t\u00eam desenvolvido um trabalho muito importante em nossa cidade, na garantia de uma alimenta\u00e7\u00e3o saud\u00e1vel. No nosso mandato vamos dispensar uma aten\u00e7\u00e3o especial \u00e0 agricultura familiar, ao empreendedorismo no campo. Contamos com a experi\u00eancia do nosso futuro governador Jer\u00f4nimo, que j\u00e1 foi secret\u00e1rio de Desenvolvimento Rural da Bahia e sabe muito bem que a agricultura familiar \u00e9 fundamental para a Bahia. Com Lula e Jer\u00f4nimo vamos aumentar os recursos destinados a este setor e estimular o surgimento de cooperativas e associa\u00e7\u00f5es, como a horta do Jo\u00e3o Paulo II,\u00a0 respons\u00e1veis pelo fortalecimento e valoriza\u00e7\u00e3o da atividade no campo&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ascom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ellen conheceu de perto a produ\u00e7\u00e3o de legumes e hortali\u00e7as produzidos na horta, p\u00f4de conversar com as agricultoras e ouvir suas conquistas e dificuldades.\u00a0<\/p>\n","protected":false},"author":5,"featured_media":397488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-397487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/09\/ellen-no-bairro.jpeg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=397487"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/397487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397488"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=397487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=397487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=397487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}