{"id":398164,"date":"2022-09-10T10:02:09","date_gmt":"2022-09-10T13:02:09","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=398164"},"modified":"2022-09-10T10:02:09","modified_gmt":"2022-09-10T13:02:09","slug":"voto-sem-mudanca","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/voto-sem-mudanca\/","title":{"rendered":"Voto sem mudan\u00e7a"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-359083 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro.jpg 1200w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Pesquisa PoderData realizada de 4 a 6 de setembro mostra que os eleitores que pretendem votar em Luiz In\u00e1cio Lula da Silva (PT) e em Jair Bolsonaro (PL) s\u00e3o os mais convictos de que n\u00e3o v\u00e3o mudar de ideia at\u00e9 o dia das elei\u00e7\u00f5es. Hoje, 89% dos que querem votar no petista e 88% do que preferem reeleger o presidente dizem ter certeza da escolha. Lula e Bolsonaro s\u00e3o os dois candidatos com pontua\u00e7\u00e3o mais alta na simula\u00e7\u00e3o de 1\u00ba turno. T\u00eam 43% e 37% das inten\u00e7\u00f5es de voto, respectivamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa PoderData realizada de 4 a 6 de setembro mostra que os eleitores que pretendem votar em Luiz In\u00e1cio Lula da Silva (PT) e em Jair Bolsonaro (PL) s\u00e3o os mais convictos de que n\u00e3o v\u00e3o mudar de ideia at\u00e9 o dia das elei\u00e7\u00f5es. Hoje, 89% dos que querem votar no p<\/p>\n","protected":false},"author":5,"featured_media":359083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6,7],"tags":[],"class_list":["post-398164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios","category-nacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/06\/lula-e-jair-bolsonaro.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/398164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=398164"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/398164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/359083"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=398164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=398164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=398164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}