{"id":398165,"date":"2022-09-10T10:04:20","date_gmt":"2022-09-10T13:04:20","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=398165"},"modified":"2022-09-10T10:04:20","modified_gmt":"2022-09-10T13:04:20","slug":"em-quem-acreditar","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/em-quem-acreditar\/","title":{"rendered":"Em quem acreditar?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-397207 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/Jair-Bolsonaro8.jpg\" alt=\"\" width=\"600\" height=\"420\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/Jair-Bolsonaro8.jpg 600w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/Jair-Bolsonaro8-300x210.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/Jair-Bolsonaro8-70x50.jpg 70w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/Jair-Bolsonaro8-160x112.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Em S\u00e3o Paulo, dois resultados, divulgados com menos de 72 horas de diferen\u00e7a, chamaram a aten\u00e7\u00e3o por diverg\u00eancias significativas nos n\u00fameros dos dois candidatos na lideran\u00e7a da disputa ao Planalto: Luiz In\u00e1cio Lula da Silva (PT) e Jair Bolsonaro (PL). Na ter\u00e7a-feira, a do Ipec apontou Lula com uma vantagem de 16 pontos. Na quarta-feira, a Genial\/Quaest mostrou o candidato \u00e0 reelei\u00e7\u00e3o e o petista em empate t\u00e9cnico, com 37% e 36% da prefer\u00eancia do eleitorado, respectivamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em S\u00e3o Paulo, dois resultados, divulgados com menos de 72 horas de diferen\u00e7a, chamaram a aten\u00e7\u00e3o por diverg\u00eancias significativas nos n\u00fameros dos dois candidatos na lideran\u00e7a da disputa ao Planalto: Luiz In\u00e1cio Lula da Silva (PT) e Jair Bolsonaro (PL). Na<\/p>\n","protected":false},"author":5,"featured_media":397207,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6,7],"tags":[],"class_list":["post-398165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios","category-nacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/08\/Jair-Bolsonaro8.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/398165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=398165"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/398165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/397207"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=398165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=398165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=398165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}