{"id":515548,"date":"2026-01-17T14:36:20","date_gmt":"2026-01-17T17:36:20","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=515548"},"modified":"2026-01-17T14:36:20","modified_gmt":"2026-01-17T17:36:20","slug":"dois-medicos-sao-mortos-a-tiros-por-outro-medico-apos-discussao-em-sp-veja-video","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/dois-medicos-sao-mortos-a-tiros-por-outro-medico-apos-discussao-em-sp-veja-video\/","title":{"rendered":"Dois m\u00e9dicos s\u00e3o mortos a tiros por outro m\u00e9dico ap\u00f3s discuss\u00e3o em SP.\u00a0Veja\u00a0v\u00eddeo"},"content":{"rendered":"<header class=\"Grid__Col-sc-owmjhw-2 ivaiSK\">\n<div class=\"HeaderNoticiaWrapper-sc-4exe2y-0 bZTBph  colunas-wrapper\">\n<h2 class=\"Text__TextBase-sc-1d75gww-0 eOYeiH noticiaCabecalho__subtitulo\">Crime ocorreu ap\u00f3s desentendimento no bairro Alphaville Plus, em Barueri (SP). O autor foi preso em flagrante<\/h2>\n<div class=\"logo-div-container\">\n<div>\n<div class=\"HeaderNoticiaWrapper__Autor-sc-4exe2y-2 ghxIAK\">Luisa Rany\/Carlos Carone, do Metr\u00f3poles<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/header>\n<div class=\"Grid__Col-sc-owmjhw-2 cgtvGh\">\n<div class=\"NoticiaInternaWrapper__ImagemDestaque-sc-481g5p-5 bBlNwq\">\n<div class=\"ImgDestaqueNoticiaWrapper-sc-1frrxvx-0 btGEwY\">\n<div class=\"ImgDestaqueNoticiaWrapper__CreditoImagem-sc-1frrxvx-1 EObEe\"><\/div>\n<figure class=\"ImgDestaqueNoticiaWrapper__Imagem-sc-1frrxvx-2 ebzoXV\">\n<div class=\"yield_master_headline_video\"><\/div>\n<\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-515549 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-620x413.webp\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-620x413.webp 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-300x200.webp 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-768x512.webp 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-160x106.webp 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-450x300.webp 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos-640x427.webp 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos.webp 900w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<\/div>\n<\/div>\n<div id=\"audiome-container\"><\/div>\n<div class=\"ConteudoNoticiaWrapper-sc-19fsm27-0 hIDPRr m-content\">\n<div class=\"ConteudoNoticiaWrapper__Artigo-sc-19fsm27-1 bpeIVq\">\n<p><strong>Dois m\u00e9dicos foram mortos a tiros por um colega de profiss\u00e3o ap\u00f3s um desentendimento.<\/strong>\u00a0O crime ocorreu em frente a um restaurante de luxo na Avenida Copacabana, no bairro Alphaville Plus, em Barueri (SP), na noite dessa sexta-feira (16\/1).<\/p>\n<div class=\"m-banner-wrap m-banner-rectangle m-publicity-content-middle\">\n<div id=\"div-gpt-ad-distrito-federal-na-mira-quadrado-1\" class=\"ad-displayed\" data-gtm-vis-recent-on-screen104869357_328=\"2639\" data-gtm-vis-first-on-screen104869357_328=\"2640\" data-gtm-vis-total-visible-time104869357_328=\"100\" data-gtm-vis-has-fired104869357_328=\"1\" data-google-query-id=\"CKS1_e2Nk5IDFTSulQIdGDIkWQ\">\n<div id=\"google_ads_iframe_\/123935210\/distrito-federal-na-mira-quadrado-1_0__container__\"><\/div>\n<\/div>\n<\/div>\n<p data-gtm-vis-recent-on-screen104869357_94=\"3801\" data-gtm-vis-first-on-screen104869357_94=\"3802\" data-gtm-vis-total-visible-time104869357_94=\"100\" data-gtm-vis-has-fired104869357_94=\"1\"><strong>Veja:<\/strong><\/p>\n<div><iframe loading=\"lazy\" title=\"Dois m\u00e9dicos s\u00e3o mortos a tiros por outro m\u00e9dico ap\u00f3s discuss\u00e3o\" src=\"https:\/\/cdn.jwplayer.com\/players\/qQIeaZVt-65fVsHCx.html\" width=\"100%\" height=\"100%\" frameborder=\"0\" scrolling=\"auto\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p><strong>O autor dos disparos \u00e9 Carlos Alberto Azevedo Silva Filho<\/strong>, que\u00a0<span class=\"highlight highlight-visible\">saiu do interior do restaurante com uma arma em punho e atirou<\/span> contra Lu\u00eds Roberto Pellegrini Gomes, de 43 anos, e Vinicius dos Santos Oliveira, de 35.<\/p>\n<p><strong>Vinicius foi atingido por dois disparos<\/strong>, um no abd\u00f4men e outro nas costas. Ele chegou a ser socorrido pelo resgate municipal e levado ao pronto-socorro do Parque Imperial,\u00a0<strong>mas n\u00e3o resistiu aos ferimentos e veio a \u00f3bito.<\/strong><\/p>\n<p>J\u00e1\u00a0<span class=\"highlight highlight-visible\">Lu\u00eds foi atingido por oito tiros<\/span>, que alcan\u00e7aram a axila esquerda, o bra\u00e7o esquerdo, a cintura, a coxa direita, as costas e o abd\u00f4men.\u00a0<strong>Assim como a outra v\u00edtima, ele foi socorrido, mas acabou morrendo.<\/strong><\/p>\n<p>Antes dos disparos, de acordo com a pol\u00edcia, Carlos teria ido ao banheiro alterado e se envolvido em uma confus\u00e3o com Vinicius e Lu\u00eds, chegando a levar socos. Em seguida, ele retornou, pegou a arma em uma bolsa e efetuou os disparos contra as v\u00edtimas.<\/p>\n<p>Segundo o boletim de ocorr\u00eancia, o autor\u00a0<strong>foi preso em flagrante por homic\u00eddio.<\/strong><\/p>\n<h3><strong>O que diz o restaurante<\/strong><\/h3>\n<p>Em nota, o restaurante El Uruguayo lamentou profundamente o ocorrido e afirmou que o local mant\u00e9m uma \u201cpol\u00edtica de toler\u00e2ncia zero \u00e0 viol\u00eancia\u201d.<\/p>\n<p>\u201cEsclarecemos que, ap\u00f3s discuss\u00f5es entre os envolvidos, de maneira desproporcional e inesperada o agressor efetuou disparos contra as v\u00edtimas na presen\u00e7a da equipe da GCM que j\u00e1 estava no local atendendo ocorr\u00eancia e foi prontamente detido\u201d, diz.<\/p>\n<p>O restaurante informou ainda que se solidariza com familiares e amigos das v\u00edtimas e que permanece \u00e0 disposi\u00e7\u00e3o das autoridades para colaborar integralmente com as investiga\u00e7\u00f5es.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dois m\u00e9dicos foram mortos a tiros por um colega de profiss\u00e3o ap\u00f3s um desentendimento.\u00a0O crime ocorreu em frente a um restaurante de luxo na Avenida Copacabana, no bairro Alphaville Plus, em Barueri (SP), na noite dessa<\/p>\n","protected":false},"author":5,"featured_media":515549,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-515548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/16c3819a-medico-preso-sp-por-matar-dois-medicos.webp","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/515548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=515548"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/515548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/515549"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=515548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=515548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=515548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}