{"id":515676,"date":"2026-01-19T08:08:09","date_gmt":"2026-01-19T11:08:09","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=515676"},"modified":"2026-01-19T08:08:09","modified_gmt":"2026-01-19T11:08:09","slug":"esse-hemisferio-nos-pertence-lula-escreve-no-nyt-sobre-eua-x-venezuela","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/esse-hemisferio-nos-pertence-lula-escreve-no-nyt-sobre-eua-x-venezuela\/","title":{"rendered":"\u2018Esse hemisf\u00e9rio nos pertence\u2019: Lula escreve no NYT sobre EUA x Venezuela"},"content":{"rendered":"<div class=\"elementor-element elementor-element-7d2fc729 titulo-post elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"7d2fc729\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n<div class=\"elementor-widget-container\"><\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-59e555ed elementor-widget elementor-widget-post-info\" data-id=\"59e555ed\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n<div class=\"elementor-widget-container\"><\/div>\n<\/div>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e25a070 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e25a070\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24f401b5\" data-id=\"24f401b5\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-6b34b66e elementor-share-buttons--view-icon elementor-share-buttons--skin-flat elementor-share-buttons--align-right elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"6b34b66e\" data-element_type=\"widget\" data-settings=\"{&quot;share_url&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blogdomagno.com.br\\\/esse-hemisferio-nos-pertence-lula-escreve-no-nyt-sobre-eua-x-venezuela\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}}\" data-widget_type=\"share-buttons.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-grid\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<div class=\"elementor-widget-container\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-515677 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-620x386.jpg\" alt=\"\" width=\"620\" height=\"386\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-620x386.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-300x187.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-768x478.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-70x45.jpg 70w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-160x100.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1-640x398.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1.jpg 1024w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/div>\n<div class=\"elementor-element elementor-element-746f5ae4 elementor-widget elementor-widget-theme-post-content\" data-id=\"746f5ae4\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n<div class=\"elementor-widget-container\">\n<div id=\"ub-expand-a0e6ceef-9ead-4190-a7c6-c1cfcad384b3\" class=\"wp-block-ub-expand ub-expand\" data-scroll-type=\"false\" data-scroll-amount=\"\" data-scroll-target=\"\">\n<div id=\"ub-expand-partial-688183e0-df4c-4482-b501-8b09c8ce20c2\" class=\"ub-expand-portion ub-expand-partial wp-block-ub-expand-portion\" aria-hidden=\"false\">\n<p>Em artigo publicado hoje no jornal New York Times, o presidente Lula (PT) criticou os bombardeios dos Estados Unidos \u00e0 Venezuela e a captura de Nicol\u00e1s Maduro, em 3 de janeiro. \u201cEsse hemisf\u00e9rio nos pertence\u201d, escreveu Lula. O artigo de opini\u00e3o publicado hoje no NYT aborda o ataque dos EUA sem precedentes a um pa\u00eds da Am\u00e9rica do Sul.<\/p>\n<p>Lula definiu a a\u00e7\u00e3o na Venezuela como \u201cmais um cap\u00edtulo lament\u00e1vel na cont\u00ednua eros\u00e3o do direito internacional e da ordem multilateral estabelecida\u201d. Entretanto, em nenhum momento o presidente brasileiro cita o nome do seu hom\u00f3logo norte-americano, Donald Trump. As informa\u00e7\u00f5es s\u00e3o do portal UOL.<\/p>\n<\/div>\n<div id=\"ub-expand-full-688183e0-df4c-4482-b501-8b09c8ce20c2\" class=\"ub-expand-portion ub-expand-full wp-block-ub-expand-portion\" aria-hidden=\"false\">\n<p>O petista ressaltou que o futuro da Venezuela cabe a seu povo. \u201cSomente um processo pol\u00edtico inclusivo, liderado por venezuelanos, conduzir\u00e1 a um futuro democr\u00e1tico e sustent\u00e1vel\u201d, escreveu, sem mencionar a ditadura sob Maduro.<\/p>\n<p>Ele comentou que essa foi a primeira vez que a Am\u00e9rica do Sul foi alvo de um ataque militar direto dos EUA em mais de 200 anos de independ\u00eancia. \u201c\u00c9 particularmente preocupante que tais pr\u00e1ticas estejam sendo infligidas \u00e0 Am\u00e9rica Latina e ao Caribe. Elas trazem viol\u00eancia e instabilidade a uma parte do mundo que luta pela paz por meio da igualdade soberana das na\u00e7\u00f5es, da rejei\u00e7\u00e3o do uso da for\u00e7a e da defesa da autodetermina\u00e7\u00e3o dos povos\u201d, diz.<\/p>\n<p>Presidente brasileiro tamb\u00e9m criticou \u201cincurs\u00f5es neocoloniais por recursos estrat\u00e9gicos\u201d, que chamou de pr\u00e1ticas \u201cultrapassadas e prejudiciais\u201d. No in\u00edcio, Trump apontou o narcoterrorismo e a amea\u00e7a \u00e0 seguran\u00e7a internacional como justificativas para a opera\u00e7\u00e3o militar. Depois, admitiu interesses na explora\u00e7\u00e3o de petr\u00f3leo na Venezuela, que tem a maior reserva do mundo.<\/p>\n<p>Petista afirmou, ainda, que chefes de Estado ou de governo podem ser responsabilizados por atentar contra a democracia e os direitos fundamentais. O presidente avalia que \u201cn\u00e3o \u00e9 leg\u00edtimo que outro Estado se arrogue o direito de fazer justi\u00e7a\u201d, como fizeram os EUA. Al\u00e9m disso, ele avalia que \u201ca\u00e7\u00f5es unilaterais amea\u00e7am a estabilidade mundial, interrompem o com\u00e9rcio e o investimento, aumentam o fluxo de refugiados e enfraquecem ainda mais a capacidade dos Estados de enfrentar o crime organizado e outros desafios transnacionais\u201d.<\/p>\n<p>L\u00edderes das grandes pot\u00eancias devem compreender que \u201cum mundo de hostilidade permanente n\u00e3o \u00e9 vi\u00e1vel\u201d, pontuou Lula. De acordo com ele, \u201cpor mais fortes que essas pot\u00eancias sejam, n\u00e3o podem se basear simplesmente no medo e na coer\u00e7\u00e3o\u201d.<\/p>\n<p>\u201cAno ap\u00f3s ano, as grandes pot\u00eancias intensificam os ataques \u00e0 autoridade das Na\u00e7\u00f5es Unidas e de seu Conselho de Seguran\u00e7a. (\u2026) Se as normas forem seguidas apenas seletivamente, a anomia se instala e enfraquece n\u00e3o apenas os Estados individualmente, mas o sistema internacional como um todo\u201d, afirmou Lula em artigo no NYT.<\/p>\n<p><strong>Artigo repete nota p\u00f3s-ataque<\/strong><\/p>\n<p>Logo ap\u00f3s a captura do ditador Maduro, Lula repudiou o epis\u00f3dio em post no X (antigo Twitter). Sem citar os EUA, ele disse que os bombardeios e a pris\u00e3o de Maduro e sua esposa, Cilia Flores, \u201cultrapassam uma linha inaceit\u00e1vel\u201d.<\/p>\n<p>Lula classificou o ataque como \u201cafronta grav\u00edssima\u201d \u00e0 soberania da Venezuela. Disse ainda que esse foi \u201cmais um precedente extremamente perigoso para toda a comunidade internacional\u201d.<\/p>\n<p>\u201cAtacar pa\u00edses, em flagrante viola\u00e7\u00e3o do direito internacional, \u00e9 o primeiro passo para um mundo de viol\u00eancia, caos e instabilidade, onde a lei do mais forte prevalece sobre o multilateralismo\u201d, disse Lula, em publica\u00e7\u00e3o no X.<\/p>\n<p>Presidente tamb\u00e9m disse na nota que Am\u00e9rica Latina e Caribe s\u00e3o \u201czona de paz\u201d. Finalizou invocando as Na\u00e7\u00f5es Unidas a responderem \u201cde forma vigorosa\u201d a esse epis\u00f3dio.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em artigo publicado hoje no jornal New York Times, o presidente Lula (PT) criticou os bombardeios dos Estados Unidos \u00e0 Venezuela e a captura de Nicol\u00e1s Maduro, em 3 de janeiro. \u201cEsse hemisf\u00e9rio nos pertence\u201d, escreveu Lula. O artigo de opini\u00e3o publicado hoje no NYT aborda o ataque dos EUA sem precedentes a um pa\u00eds [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":515677,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,7],"tags":[],"class_list":["post-515676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-nacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/lula-quaest-1024x637-1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/515676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=515676"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/515676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/515677"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=515676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=515676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=515676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}