{"id":515809,"date":"2026-01-20T02:57:17","date_gmt":"2026-01-20T05:57:17","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=515809"},"modified":"2026-01-20T02:57:17","modified_gmt":"2026-01-20T05:57:17","slug":"segue-a-todo-vapor-construcao-do-novo-mercado-municipal-de-sobradinho","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/segue-a-todo-vapor-construcao-do-novo-mercado-municipal-de-sobradinho\/","title":{"rendered":"Segue a todo vapor constru\u00e7\u00e3o do novo Mercado Municipal de Sobradinho"},"content":{"rendered":"<p><strong>Reda\u00e7\u00e3o<\/strong><\/p>\n<p>A obra de constru\u00e7\u00e3o do Mercado Municipal de Sobradinho segue a todo vapor. O novo Mercado est\u00e1 sendo constru\u00eddo com a melhor qualidade poss\u00edvel para atender a demanda da cidade e tamb\u00e9m da regi\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-515810 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-620x348.png\" alt=\"\" width=\"620\" height=\"348\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-620x348.png 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-300x169.png 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-768x432.png 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-160x90.png 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-480x270.png 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado-640x360.png 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado.png 808w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Muito em breve, Sobradinho vai contar com um verdadeiro shopping popular, com estrutura moderna, novos quiosques e mais dignidade para os comerciantes e consumidores da cidade.<\/p>\n<p>A obra, fruto da parceria com o Governo do Estado da Bahia, por meio do governador Jer\u00f4nimo Rodrigues, tem investimento de R$ 4 milh\u00f5es, al\u00e9m de uma importante contrapartida do nosso munic\u00edpio de mais de R$ 400 mil.<\/p>\n<p>O espa\u00e7o vai contar com um ambiente confort\u00e1vel, moderno, apropriado para as compras e, sobretudo, para o lazer e conviv\u00eancia da popula\u00e7\u00e3o local e turistas. Essas s\u00e3o as principais caracter\u00edsticas do novo Mercado.<\/p>\n<div style=\"width: 1276px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-515809-1\" width=\"1276\" height=\"720\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/WhatsApp-Video-2026-01-19-at-09.21.55.mp4?_=1\" \/><a href=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/WhatsApp-Video-2026-01-19-at-09.21.55.mp4\">https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/WhatsApp-Video-2026-01-19-at-09.21.55.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A obra de constru\u00e7\u00e3o do Mercado Municipal de Sobradinho segue a todo vapor. O novo Mercado est\u00e1 sendo constru\u00eddo com a melhor qualidade poss\u00edvel para atender a demanda da cidade e tamb\u00e9m da regi\u00e3o.\u00a0\u00a0<\/p>\n","protected":false},"author":5,"featured_media":515810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-515809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2026\/01\/novo-mercado.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/515809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=515809"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/515809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/515810"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=515809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=515809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=515809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}